{"id":3614,"date":"2023-04-05T08:59:00","date_gmt":"2023-04-05T08:59:00","guid":{"rendered":"https:\/\/favdevs.com\/demos\/wp\/techza\/?page_id=3614"},"modified":"2026-01-28T09:25:18","modified_gmt":"2026-01-28T14:25:18","slug":"who-we-are","status":"publish","type":"page","link":"https:\/\/suplos.com\/en\/sobre-nosotros\/quienes-somos\/","title":{"rendered":"Who are we"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3614\" class=\"elementor elementor-3614\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f78d1e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7f78d1e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-871a102\" data-id=\"871a102\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-228e13b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"228e13b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c87a94d\" data-id=\"c87a94d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b02eabc elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"b02eabc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sobre nosotros<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f620170 elementor-widget elementor-widget-text-editor\" data-id=\"f620170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Creamos soluciones que automatizan, conectan y mejoran los procesos de Compras y Finanzas<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b648573 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b648573\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0975956\" data-id=\"0975956\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-243fb59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"243fb59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d9790c9 elementor-invisible\" data-id=\"d9790c9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e3eae9 elementor-widget elementor-widget-image\" data-id=\"3e3eae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2047\" height=\"1366\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92.jpg\" class=\"attachment-full size-full wp-image-15455\" alt=\"\" srcset=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92.jpg 2047w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92-300x200.jpg 300w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92-1024x683.jpg 1024w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92-768x513.jpg 768w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92-1536x1025.jpg 1536w\" sizes=\"(max-width: 2047px) 100vw, 2047px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ba75108\" data-id=\"ba75108\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a49df6d elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"a49df6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra historia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d8cae2 elementor-widget elementor-widget-text-editor\" data-id=\"4d8cae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Suplos naci\u00f3 en 2015 con un prop\u00f3sito claro: optimizar el abastecimiento a trav\u00e9s de tecnolog\u00eda.<\/p>\n<p>Desde entonces, hemos desarrollado un ecosistema digital que automatiza todo el ciclo de abastecimiento, desde el presupuesto hasta el pago, con soluciones que integran IA, anal\u00edtica avanzada y acompa\u00f1amiento de expertos.<\/p>\n<p>Nuestro equipo, 100% latinoamericano, combina talento t\u00e9cnico con visi\u00f3n estrat\u00e9gica para generar valor real en cada empresa que conf\u00eda en nosotros<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-212030c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"212030c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82a4b23\" data-id=\"82a4b23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0bccee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0bccee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e136cb6\" data-id=\"e136cb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5869e7 elementor-widget elementor-widget-heading\" data-id=\"f5869e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lo que nos mueve<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81ba52b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81ba52b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1c50d0d\" data-id=\"1c50d0d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8442b61 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8442b61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-01.png\" class=\"attachment-full size-full wp-image-16649\" alt=\"\" srcset=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-01.png 900w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-01-300x300.png 300w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-01-150x150.png 150w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-01-768x768.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Innovaci\u00f3n que simplifica<\/h3><p class=\"elementor-image-box-description\">Usamos tecnolog\u00eda para resolver problemas reales y hacer los procesos m\u00e1s eficientes.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6ae43ec\" data-id=\"6ae43ec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2947aa9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2947aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-02.png\" class=\"attachment-full size-full wp-image-16650\" alt=\"\" srcset=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-02.png 900w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-02-300x300.png 300w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-02-150x150.png 150w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-02-768x768.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Compromiso con el impacto<\/h3><p class=\"elementor-image-box-description\">Buscamos generar valor tangible para nuestros clientes y sus cadenas de suministro.\n\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d6dfe6a\" data-id=\"d6dfe6a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0920a4f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0920a4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-03.png\" class=\"attachment-full size-full wp-image-16651\" alt=\"\" srcset=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-03.png 900w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-03-300x300.png 300w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-03-150x150.png 150w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-03-768x768.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Transparencia en cada acci\u00f3n<\/h3><p class=\"elementor-image-box-description\">Promovemos procesos confiables, trazables y colaborativos.\n\n\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b574fa5\" data-id=\"b574fa5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8160f22 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8160f22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-04.png\" class=\"attachment-full size-full wp-image-16652\" alt=\"\" srcset=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-04.png 900w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-04-300x300.png 300w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-04-150x150.png 150w, https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Iconos-quienes-somos-04-768x768.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Trabajo con prop\u00f3sito<\/h3><p class=\"elementor-image-box-description\">Creamos soluciones pensando en las personas y en el desarrollo de la regi\u00f3n.\n\n\n\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-028fdbf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"028fdbf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-255f61d\" data-id=\"255f61d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e1af5b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1af5b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e48e4d0\" data-id=\"e48e4d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d13fdd8 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"d13fdd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres ser nuestro aliado comercial?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e773ef elementor-widget elementor-widget-text-editor\" data-id=\"5e773ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si est\u00e1s en una organizaci\u00f3n o eres un consultor con conocimiento en la Cadena de Abastecimiento y\/o Soluciones para el Financiamiento de las cuentas por cobrar (o cuentas por pagar, seg\u00fan corresponda) en empresas mediante las modalidades de Pre-factoring, Factoring y\/o Confirming y quieres establecer una alianza para la implementaci\u00f3n de nuestros servicios y soluciones, completa el siguiente formulario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c4c728d\" data-id=\"c4c728d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df9c478 elementor-widget__width-initial elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"df9c478\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;30&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Formulario partner\" aria-label=\"Formulario partner\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"3614\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"df9c478\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Qui\u00e9nes somos - suplos.com\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"3614\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nombre\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCorreo corporativo\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Correo corporativo\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-message elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmpresa\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[message]\" id=\"form-field-message\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Empresa\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_f39d235 elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f39d235\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tN\u00famero de contacto\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_f39d235]\" id=\"form-field-field_f39d235\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"N\u00famero de contacto\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Somente n\u00fameros e caracteres de telefone (#, -, *, etc.) s\u00e3o aceitos.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_0c34ddc elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_0c34ddc\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u00bfQu\u00e9 interacci\u00f3n de imaginas?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[field_0c34ddc]\" id=\"form-field-field_0c34ddc\" rows=\"4\" placeholder=\"\u00bfQu\u00e9 tipo de interacci\u00f3n te imaginas?\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_7beb39b elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_7beb39b]\" id=\"form-field-field_7beb39b\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-field_7beb39b\">Al enviar este formulario, acepto el tratamiento de mis datos personales conforme a la <a href=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/12\/Politica-de-Datos-Suplos.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Pol\u00edtica de Tratamiento de Datos<\/a> de Suplos.\n<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_2f05314 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_2f05314\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcYiFcdAAAAAPwG_PTzrOIhOKgNk-oOOBy9DtgZ\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-30 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-paper-plane\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M440 6.5L24 246.4c-34.4 19.9-31.1 70.8 5.7 85.9L144 379.6V464c0 46.4 59.2 65.5 86.6 28.6l43.8-59.1 111.9 46.2c5.9 2.4 12.1 3.6 18.3 3.6 8.2 0 16.3-2.1 23.6-6.2 12.8-7.2 21.6-20 23.9-34.5l59.4-387.2c6.1-40.1-36.9-68.8-71.5-48.9zM192 464v-64.6l36.6 15.1L192 464zm212.6-28.7l-153.8-63.5L391 169.5c10.7-15.5-9.5-33.5-23.7-21.2L155.8 332.6 48 288 464 48l-59.4 387.3z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94832a9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"94832a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecb3c4e\" data-id=\"ecb3c4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1135f0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1135f0d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-245d95b\" data-id=\"245d95b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f616878 elementor-widget elementor-widget-heading\" data-id=\"f616878\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suplos en medios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1ce8c79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ce8c79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2488b19\" data-id=\"2488b19\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e465f6 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"2e465f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:3000,&quot;lazyload&quot;:&quot;yes&quot;,&quot;speed&quot;:600,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/La-nota-economica_Mesa-de-trabajo-1-150x150.png\" alt=\"La nota economica_Mesa de trabajo 1\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-04-150x150.png\" alt=\"250x250-04\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-06-150x150.png\" alt=\"250x250-06\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-08-150x150.png\" alt=\"250x250-08\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-09-150x150.png\" alt=\"250x250-09\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-10-150x150.png\" alt=\"250x250-10\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-12-150x150.png\" alt=\"250x250-12\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-13-150x150.png\" alt=\"250x250-13\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-14-150x150.png\" alt=\"250x250-14\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-15-150x150.png\" alt=\"250x250-15\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-16-150x150.png\" alt=\"250x250-16\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/250x250-17-150x150.png\" alt=\"250x250-17\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Sin-titulo-2-02-150x150.png\" alt=\"Sin t\u00edtulo-2-02\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Sin-titulo-2-03-150x150.png\" alt=\"Sin t\u00edtulo-2-03\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Sin-titulo-2-05-150x150.png\" alt=\"Sin t\u00edtulo-2-05\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 de 16\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/suplos.com\/wp-content\/uploads\/2025\/07\/Sin-titulo-2-11-150x150.png\" alt=\"Sin t\u00edtulo-2-11\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b8f776 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5b8f776\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f15f9e2\" data-id=\"4f15f9e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ee2a5ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ee2a5ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a52520c\" data-id=\"4a52520c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38aacb71 elementor-widget elementor-widget-heading\" data-id=\"38aacb71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres transformar tu gesti\u00f3n de Abastecimiento?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3832e2b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3832e2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2MDY0IiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cont\u00e1ctanos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sobre nosotros Creamos soluciones que automatizan, conectan y mejoran los procesos de Compras y Finanzas Nuestra historia Suplos naci\u00f3 en 2015 con un prop\u00f3sito claro: optimizar el abastecimiento a trav\u00e9s de tecnolog\u00eda. Desde entonces, hemos desarrollado un ecosistema digital que automatiza todo el ciclo de abastecimiento, desde el presupuesto hasta el pago, con soluciones que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":15415,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-3614","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qui\u00e9nes somos - suplos.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/en\/about-us\/who-we-are\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9nes somos - suplos.com\" \/>\n<meta property=\"og:description\" content=\"Sobre nosotros Creamos soluciones que automatizan, conectan y mejoran los procesos de Compras y Finanzas Nuestra historia Suplos naci\u00f3 en 2015 con un prop\u00f3sito claro: optimizar el abastecimiento a trav\u00e9s de tecnolog\u00eda. Desde entonces, hemos desarrollado un ecosistema digital que automatiza todo el ciclo de abastecimiento, desde el presupuesto hasta el pago, con soluciones que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/en\/about-us\/who-we-are\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T14:25:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/\",\"name\":\"Qui\u00e9nes somos - suplos.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Suplos-2021-92.jpg\",\"datePublished\":\"2023-04-05T08:59:00+00:00\",\"dateModified\":\"2026-01-28T14:25:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/#primaryimage\",\"url\":\"http:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Suplos-2021-92.jpg\",\"contentUrl\":\"http:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Suplos-2021-92.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/sobre-nosotros\\\/quienes-somos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre nosotros\",\"item\":\"https:\\\/\\\/limegreen-hummingbird-563256.hostingersite.com\\\/sobre-nosotros\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qui\u00e9nes somos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About us - suplos.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/en\/about-us\/who-we-are\/","og_locale":"en_US","og_type":"article","og_title":"Qui\u00e9nes somos - suplos.com","og_description":"Sobre nosotros Creamos soluciones que automatizan, conectan y mejoran los procesos de Compras y Finanzas Nuestra historia Suplos naci\u00f3 en 2015 con un prop\u00f3sito claro: optimizar el abastecimiento a trav\u00e9s de tecnolog\u00eda. Desde entonces, hemos desarrollado un ecosistema digital que automatiza todo el ciclo de abastecimiento, desde el presupuesto hasta el pago, con soluciones que [&hellip;]","og_url":"https:\/\/suplos.com\/en\/about-us\/who-we-are\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_modified_time":"2026-01-28T14:25:18+00:00","og_image":[{"url":"http:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/","url":"https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/","name":"About us - suplos.com","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/#primaryimage"},"thumbnailUrl":"http:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92.jpg","datePublished":"2023-04-05T08:59:00+00:00","dateModified":"2026-01-28T14:25:18+00:00","breadcrumb":{"@id":"https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/#primaryimage","url":"http:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92.jpg","contentUrl":"http:\/\/suplos.com\/wp-content\/uploads\/2025\/06\/Suplos-2021-92.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/sobre-nosotros\/quienes-somos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Sobre nosotros","item":"https:\/\/limegreen-hummingbird-563256.hostingersite.com\/sobre-nosotros\/"},{"@type":"ListItem","position":3,"name":"Qui\u00e9nes somos"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Procurement Management Software","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/pages\/3614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/comments?post=3614"}],"version-history":[{"count":143,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/pages\/3614\/revisions"}],"predecessor-version":[{"id":19312,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/pages\/3614\/revisions\/19312"}],"up":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/pages\/15415"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media?parent=3614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}