{"id":1641,"date":"2021-06-03T15:28:52","date_gmt":"2021-06-03T15:28:52","guid":{"rendered":"https:\/\/suplos.com\/?p=1641"},"modified":"2025-07-09T12:38:44","modified_gmt":"2025-07-09T17:38:44","slug":"energy-sector-latin-america-2021","status":"publish","type":"post","link":"https:\/\/suplos.com\/en\/oil-gas\/sector-energetico-latinoamerica-2021\/","title":{"rendered":"Latin America's energy sector for the second half of 2021: The good, the bad and the ugly"},"content":{"rendered":"\n<p>A pesar de una Pandemia devastadora, han surgido varios desarrollos positivos en el sector energ\u00e9tico latinoamericano. El precio de la energ\u00eda renovable y tecnolog\u00edas relacionadas, como los precios de las bater\u00edas, est\u00e1n en sus m\u00ednimos. La arremetida de los gobiernos por tener una emisi\u00f3n neutral de carbono est\u00e1 ayudando a generar la transici\u00f3n energ\u00e9tica global. Sin embargo, los retos a\u00fan persisten. La dependencia que tiene la regi\u00f3n en China genera fricci\u00f3n para incrementar la cadena de valor, <strong>el COVID-19 ha cedido terreno ganado en empleo por d\u00e9cadas<\/strong>, lo cual ha desembocado a que millones de latinoamericanos est\u00e9n en pobreza, exacerbando las crisis sociales y postergando los grandes proyectos de infraestructura que permitir\u00edan dar un cambio en la din\u00e1mica del sector.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lo bueno: precios estables crecientes y nuevas oportunidades en renovables<\/h2>\n\n\n\n<p>Existe un gran consenso en los Gobiernos latinoamericanos e inversionistas de la necesidad de disminuir la emisi\u00f3n de Carbono.<\/p>\n\n\n\n<p>Un ejemplo de lo anterior es ECOPETROL. La estatal colombiana con su programa SosTecnibilidad busca con un modelo de contribuci\u00f3n y generaci\u00f3n de valor a la sociedad, a trav\u00e9s de soluciones innovadoras y tecnol\u00f3gicas propender por el desarrollo econ\u00f3micos, social y ambiental. Las emisiones netas de Carbono para ECOPETROL seg\u00fan su plan estrat\u00e9gico de cero est\u00e1n para el 2050.<strong><\/strong><\/p>\n\n\n\n<p>El incremento del precio del petr\u00f3leo y de otras materias primas del sector de Oil &amp; Gas, junto con las eficiencias derivadas de periodos de crisis y austeridad de a\u00f1os anteriores ha permitido que las empresas hoy tengan una eficiencia operacional y que est\u00e9n logrando mejores m\u00e1rgenes operacionales.<\/p>\n\n\n\n<p>Estos <strong>excedentes de liquidez, aunados con tasas de financiaci\u00f3n menores, est\u00e1n siendo usados por las empresas para invertir en su capacidad instalada<\/strong>, nuevas tecnolog\u00edas y en algunos casos inversiones para lograr una transici\u00f3n energ\u00e9tica definitiva en Latam.<\/p>\n\n\n\n<p>Prueba de ello es que 2 de los pa\u00edses con mayor generaci\u00f3n de energ\u00eda e\u00f3lica fueron Argentina y Brasil. Mientras que Brasil, Chile, Per\u00fa y Mexico se destacan por ofrecer al mercado los m\u00ednimos precios en subastas de energ\u00eda solar fotovoltaica.<\/p>\n\n\n\n<p><strong><em>Precio Promedio de proyectos solares y e\u00f3licos en USD, de subastas recientes en 6 mercados de Latam. [*]<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2021\/06\/Imagen1.gif\" alt=\"\" class=\"wp-image-1642\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Lo malo: crisis social en comunidades locales<\/h3>\n\n\n\n<p>Al tener en la regi\u00f3n&nbsp; el desempleo m\u00e1s alto en una d\u00e9cada y 45 millones de personas dentro de la pobreza, se espera que los votantes tengan preferencia prioritaria por pol\u00edticas de inversi\u00f3n social, <strong>m\u00e1s all\u00e1 de costosos y grandes proyectos de generaci\u00f3n de energ\u00eda apalancados con recursos p\u00fablicos<\/strong>. La frustraci\u00f3n social en las regiones har\u00eda que los proyectos existentes y nuevos, requieran m\u00e1s transferencias fiscales que se queden en las comunidades para contar con su respaldo.<\/p>\n\n\n\n<p>En M\u00e9xico, por ejemplo, se ha evidenciado c\u00f3mo las comunidades locales se han manifestado en contra de las granjas e\u00f3licas en Oaxaca, argumentando ruido excesivo y filtraci\u00f3n de material contaminante de las turbinas. En Guayana, 9 billones de barriles fueron descubiertos y existe una presi\u00f3n permanente para renegociar los t\u00e9rminos de extracci\u00f3n con Exxon para emplear a la mayor cantidad de personas locales en todo el desarrollo del proyecto desde la construcci\u00f3n hasta la operaci\u00f3n.<\/p>\n\n\n\n<p>Otro ejemplo reciente es Colombia en donde hemos visto como algunas empresas han tenido que cesar sus actividades por la protesta social que tiene bloqueos en las v\u00edas. <strong>Para garantizar los desarrollos nuevos y existentes en el largo plazo, es vital que tanto las empresas como las autoridades estatales locales puedan dialogar y entender las expectativas que tienen las comunidades locales.<\/strong> De esta forma, se puede recibir retroalimentaci\u00f3n vital con el tipo de inversi\u00f3n y apoyo que la comunidad local espera recibir. Este dialogo generar\u00e1 buena disposici\u00f3n y apoyo local.<em><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lo feo: pocos proyectos en la generaci\u00f3n de valor agregado y la dependencia de China<\/h3>\n\n\n\n<p>En Latinoam\u00e9rica, pa\u00edses como Brasil contin\u00faan imponiendo tarifas arancelarias del 65% en algunos componentes de las bater\u00edas, haciendo que los grandes proyectos de manufactura de &nbsp;bater\u00edas sean inviables.<\/p>\n\n\n\n<p>Chile, Argentina y Bolivia que <strong>en conjunto contienen 58% de las reservas identificadas de Litio, tampoco han sido capaces de desarrollar activos para el procesamiento de bater\u00edas<\/strong>, lo cual les permitir\u00eda ascender dentro de la cadena de valor. Fue as\u00ed, como el proyecto Lilpi que pretend\u00eda convertirse en el primera planta para el procesamiento de Litio comercial, fue anulada por el gobierno en 2019 por protestas de la comunidad local de Potosi.<\/p>\n\n\n\n<p>Lo que ha continuado sucediendo en los pa\u00edses en Latam es la continua exportaci\u00f3n de este tipo de materias primas, en donde solo China es responsable de recibir entre el 50% al 70% del Litio generado a nivel mundial junto con el cobalto refinado. <strong>China tambi\u00e9n controla entre el 85% al 90% de las tierras raras, las cuales son vitales para todo tipo de productos electr\u00f3nicos.<\/strong><strong><\/strong><\/p>\n\n\n\n<p>Dado que China produce el 63% de las bater\u00edas de litio en el mundo, adem\u00e1s del 70% del grafito, una iniciativa que ser\u00eda de f\u00e1cil ejecuci\u00f3n por parte de este pa\u00eds es imponer impuestos o restricciones de esos bienes, lo que impedir\u00eda el desarrollo de productos esenciales para energ\u00eda renovable. As\u00ed, <strong>ocurri\u00f3 con Jap\u00f3n cuando China restringi\u00f3 sus exportaciones de tierras raras por 50 d\u00edas haciendo que los precios de esas materias primeras se incrementaran en un 350%<\/strong>. Durante el 2021 es probable que China siga imponiendo restricciones a la exportaci\u00f3n de estas materias primas USA por el conflicto tripartita entre USA- China y Taiwan. Para USA estos elementos son vitales para la fabricaci\u00f3n de armamento.<\/p>\n\n\n\n<p>Los pa\u00edses latinoamericanos cada vez se est\u00e1n viendo forzados a tomar un bando entre China y Estados Unidos. Escoger a uno u otro, tiene implicaciones que puede contener disrupciones en la cadena de suministro provenientes de fricciones y trabas del bando no seleccionado.<strong><\/strong><\/p>\n\n\n\n<p>Adem\u00e1s de lo anterior, los latinoamericanos se est\u00e1n enfrentando con mayor dinamismo con otro factor \u201cfeo\u201d y es el ascenso de los l\u00edderes populistas. Brasil, M\u00e9xico y Argentina ya cuentan con un l\u00edder de estas caracter\u00edsticas, mientras que podr\u00eda suceder lo mismo en las pr\u00f3ximas elecciones en Per\u00fa y Colombia. Las acciones presidenciales de este tipo de l\u00edderes, disminuyen la confianza inversionista e impiden un desarrollo m\u00e1s abierto, asequible y competitivo del mercado energ\u00e9tico.<\/p>\n\n\n\n<p>El crecimiento en 2021 del consumo, viajes a\u00e9reos, comercial e industrial apunta hacia un crecimiento sostenido por energ\u00eda de Latam. <strong>Dado el hueco fiscal de los gobiernos latinoamericanos, por ahora no se pueden permitir la inversi\u00f3n en la expansi\u00f3n de su capacidad energ\u00e9tica.<\/strong> Sin embargo, las oportunidades abundan en Latam para el desarrollo de nuevos proyectos de energ\u00eda de car\u00e1cter privado. Es crucial para su desarrollo efectivo, navegar estos retos con una debida diligencia cuidadosa que permita leer adem\u00e1s de las bondades del proyecto el clima macroecon\u00f3mico y pol\u00edtico.<strong><\/strong><\/p>\n\n\n\n<p><em>[*]Elaboraci\u00f3n propia y de la referencia relacionada.<\/em><\/p>\n\n\n\n<p><em>[**]Tomado del ingl\u00e9s:<\/em><\/p>\n\n\n\n<p><em>Autor:&nbsp;<\/em><a class=\"rank-math-link\" href=\"https:\/\/americasmi.com\/insights\/author\/arthur-deakin\/\"><em>Arthur Deakin<\/em><\/a><\/p>\n\n\n\n<p><em>Publicado en :&nbsp;<a href=\"https:\/\/americasmi.com\/insights\/author\/arthur-deakin\/\" class=\"rank-math-link\">Febrero<u> 28 del 2021<\/u><\/a><\/em><\/p>\n\n\n\n<p><em>En&nbsp;<\/em><a href=\"https:\/\/americasmi.com\/insights\/category\/energy\/\"><em>Energy<\/em><\/a><em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de una Pandemia devastadora, han surgido varios desarrollos positivos en el sector energ\u00e9tico latinoamericano. El precio de la energ\u00eda renovable y tecnolog\u00edas relacionadas, como los precios de las bater\u00edas, est\u00e1n en sus m\u00ednimos. La arremetida de los gobiernos por tener una emisi\u00f3n neutral de carbono est\u00e1 ayudando a generar la transici\u00f3n energ\u00e9tica global. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17407,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-1641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oil-gas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sector energ\u00e9tico en Latinoam\u00e9rica para 2021- II | Suplos<\/title>\n<meta name=\"description\" content=\"A pesar de una Pandemia devastadora, han surgido varios desarrollos positivos en el sector energ\u00e9tico latinoamericano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/en\/oil-gas\/energy-sector-latin-america-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sector energ\u00e9tico en Latinoam\u00e9rica para 2021- II | Suplos\" \/>\n<meta property=\"og:description\" content=\"A pesar de una Pandemia devastadora, han surgido varios desarrollos positivos en el sector energ\u00e9tico latinoamericano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/en\/oil-gas\/energy-sector-latin-america-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-03T15:28:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T17:38:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2021\/06\/Articulo-portada-min.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniel Obregon Daniel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Obregon Daniel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/\"},\"author\":{\"name\":\"Daniel Obregon Daniel\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/5859c236dc6f1960bec711cb6293e169\"},\"headline\":\"Sector energ\u00e9tico en Latinoam\u00e9rica para el segundo semestre 2021: Lo bueno, lo malo y lo feo\",\"datePublished\":\"2021-06-03T15:28:52+00:00\",\"dateModified\":\"2025-07-09T17:38:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/\"},\"wordCount\":1242,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Articulo-portada-min.png\",\"articleSection\":[\"Oil &amp; Gas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/\",\"name\":\"Sector energ\u00e9tico en Latinoam\u00e9rica para 2021- II | Suplos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Articulo-portada-min.png\",\"datePublished\":\"2021-06-03T15:28:52+00:00\",\"dateModified\":\"2025-07-09T17:38:44+00:00\",\"description\":\"A pesar de una Pandemia devastadora, han surgido varios desarrollos positivos en el sector energ\u00e9tico latinoamericano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Articulo-portada-min.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Articulo-portada-min.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/oil-gas\\\/sector-energetico-latinoamerica-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sector energ\u00e9tico en Latinoam\u00e9rica para el segundo semestre 2021: Lo bueno, lo malo y lo feo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/5859c236dc6f1960bec711cb6293e169\",\"name\":\"Daniel Obregon Daniel\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/en\\\/author\\\/dobregon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energy sector in Latin America by 2021- II | Suplos","description":"Despite a devastating pandemic, there have been several positive developments in the Latin American energy sector.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/en\/oil-gas\/energy-sector-latin-america-2021\/","og_locale":"en_US","og_type":"article","og_title":"Sector energ\u00e9tico en Latinoam\u00e9rica para 2021- II | Suplos","og_description":"A pesar de una Pandemia devastadora, han surgido varios desarrollos positivos en el sector energ\u00e9tico latinoamericano.","og_url":"https:\/\/suplos.com\/en\/oil-gas\/energy-sector-latin-america-2021\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2021-06-03T15:28:52+00:00","article_modified_time":"2025-07-09T17:38:44+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/06\/Articulo-portada-min.png","type":"image\/png"}],"author":"Daniel Obregon Daniel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Obregon Daniel","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/"},"author":{"name":"Daniel Obregon Daniel","@id":"https:\/\/suplos.com\/#\/schema\/person\/5859c236dc6f1960bec711cb6293e169"},"headline":"Sector energ\u00e9tico en Latinoam\u00e9rica para el segundo semestre 2021: Lo bueno, lo malo y lo feo","datePublished":"2021-06-03T15:28:52+00:00","dateModified":"2025-07-09T17:38:44+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/"},"wordCount":1242,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/06\/Articulo-portada-min.png","articleSection":["Oil &amp; Gas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/","url":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/","name":"Energy sector in Latin America by 2021- II | Suplos","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/06\/Articulo-portada-min.png","datePublished":"2021-06-03T15:28:52+00:00","dateModified":"2025-07-09T17:38:44+00:00","description":"Despite a devastating pandemic, there have been several positive developments in the Latin American energy sector.","breadcrumb":{"@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/06\/Articulo-portada-min.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/06\/Articulo-portada-min.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/oil-gas\/sector-energetico-latinoamerica-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Sector energ\u00e9tico en Latinoam\u00e9rica para el segundo semestre 2021: Lo bueno, lo malo y lo feo"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Procurement Management Software","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/5859c236dc6f1960bec711cb6293e169","name":"Daniel Obregon Daniel","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/en\/author\/dobregon\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/comments?post=1641"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1641\/revisions"}],"predecessor-version":[{"id":17412,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1641\/revisions\/17412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media\/17407"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media?parent=1641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/categories?post=1641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/tags?post=1641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}