{"id":1872,"date":"2021-10-07T19:20:19","date_gmt":"2021-10-07T19:20:19","guid":{"rendered":"https:\/\/suplos.com\/?p=1872"},"modified":"2025-07-06T14:34:06","modified_gmt":"2025-07-06T19:34:06","slug":"positive-technology-dependence","status":"publish","type":"post","link":"https:\/\/suplos.com\/en\/transformacion-digital\/dependencia-tecnologica-positiva\/","title":{"rendered":"Positive technology dependence"},"content":{"rendered":"<p>La constante y, hasta en cierto punto, natural interacci\u00f3n que tenemos d\u00eda a d\u00eda con la tecnolog\u00eda ha generado un sinn\u00famero de debates sobre qu\u00e9 tan dependientes somos y hasta qu\u00e9 punto esta dependencia empieza a jugar un papel negativo en nuestras vidas.<\/p>\n\n\n\n<p>Los avances y aportes que se han logrado desarrollar gracias a avances tecnol\u00f3gicos saltan a la vista en nuestro d\u00eda a d\u00eda en diferentes industrias, tales como: transporte, medicina, telecomunicaciones, negocios, entre otras. El dilema se complejiza cuando se evidencia que el aporte tecnol\u00f3gico no se se transforma en un entregable positivo sino que al contrario se vuelve un ente pasivo que muta en tiempos muertos o decanta en complejizaci\u00f3n de tareas (lo sencillo se complica tanto que se vuelve dif\u00edcil de administrar).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ventajas y desventajas de la dependencia positiva<\/h2>\n\n\n\n<p>Diferentes estudios resaltan las ventajas y desventajas que ha representado la escalada tecnol\u00f3gica en la vida del ser humano. Como muestra de ello, un estudio realizado por la Universidad de Stanford en 2020 hace una aproximaci\u00f3n al tema enfocando su an\u00e1lisis principalmente en la tecnolog\u00eda aplicada a los negocios (herramientas facilitadoras que simplifiquen tareas de alta carga operativa). Haciendo una extracci\u00f3n muy ejecutiva del estudio <strong>se pueden precisar 3 puntos a considerar cuando se piensa en generar una dependencia positiva de la tecnolog\u00eda en los negocios<\/strong>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Las herramientas tecnol\u00f3gicas no se imponen<\/h3>\n\n\n\n<p>&nbsp;La presi\u00f3n impuesta por la pandemia ha generado que todas las empresas sientan la necesidad de sofisticar sus procesos apalanc\u00e1ndose en tecnolog\u00eda. <strong>Lo malo del caso es cuando no se reconoce el \u201cmomento de desarrollo tecnol\u00f3gico\u201d de la empresa<\/strong> y se busca imponer o integrar el sistema m\u00e1s robusto del momento sin darse a la tarea de hacer el desarrollo progresivo. En muchos casos esta implementaci\u00f3n forzada termina en grandes p\u00e9rdidas de dinero y generando retrocesos en lugar de cambios positivos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Complemento facilitador<\/h3>\n\n\n\n<p>Pruebas realizadas por el estudio encontraron que en m\u00e1s de 500 empresas evaluadas, cerca del <strong>44,5% de los procesos en los que se hab\u00eda logrado una asociaci\u00f3n favorable de tecnolog\u00eda, la eficiencia en tareas y ahorros superaban la tasa del 36,2%.<\/strong> Cuando el desarrollo tecnol\u00f3gico entra a complementar positivamente los procesos existentes se logran ahorros sostenibles en el tiempo. En caso contrario, cuando la tecnolog\u00eda se volv\u00eda un \u201cstopper\u201d por su complejidad generaba repeticiones innecesarias o encarecia los procesos en aproximadamente un 28,4%.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. M\u00e1s estrateg\u00eda, menos repetici\u00f3n<\/h3>\n\n\n\n<p>Cuando la herramienta tecnol\u00f3gica permite enfocar esfuerzos en tareas estrat\u00e9gicas, de an\u00e1lisis y reposa los procesos repetitivos en la m\u00e1quina, se empieza a dar un verdadero giro hac\u00eda la dependencia positiva. No consume del equipo m\u00e1s que lo necesario para depositar en este las funciones de toma de decisiones y an\u00e1lisis del norte de la empresa. <strong>El 69,4% de las empresas analizadas en el estudio enfocaron sus esfuerzos por esta v\u00eda<\/strong>, logrando as\u00ed un impacto en generaci\u00f3n de valor x2,4 veces lo que hac\u00edan cuando su foco estaba en lo netamente operativo.<\/p>","protected":false},"excerpt":{"rendered":"<p>La constante y, hasta en cierto punto, natural interacci\u00f3n que tenemos d\u00eda a d\u00eda con la tecnolog\u00eda ha generado un sinn\u00famero de debates sobre qu\u00e9 tan dependientes somos y hasta qu\u00e9 punto esta dependencia empieza a jugar un papel negativo en nuestras vidas. Los avances y aportes que se han logrado desarrollar gracias a avances [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":16962,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-1872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transformacion-digital"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dependencia tecnol\u00f3gica positiva | Suplos<\/title>\n<meta name=\"description\" content=\"Un an\u00e1lisis sobre c\u00f3mo la tecnolog\u00eda ha generado un sinn\u00famero de debates sobre qu\u00e9 tan dependientes somos y hasta qu\u00e9 punto es negativo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/en\/digital-transformation\/positive-technology-dependence\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dependencia tecnol\u00f3gica positiva | Suplos\" \/>\n<meta property=\"og:description\" content=\"Un an\u00e1lisis sobre c\u00f3mo la tecnolog\u00eda ha generado un sinn\u00famero de debates sobre qu\u00e9 tan dependientes somos y hasta qu\u00e9 punto es negativo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/en\/digital-transformation\/positive-technology-dependence\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-07T19:20:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T19:34:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2021\/10\/Articulo-Portada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andres Sarmiento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Sarmiento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/\"},\"author\":{\"name\":\"Andres Sarmiento\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\"},\"headline\":\"Dependencia tecnol\u00f3gica positiva\",\"datePublished\":\"2021-10-07T19:20:19+00:00\",\"dateModified\":\"2025-07-06T19:34:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/\"},\"wordCount\":530,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulo-Portada.png\",\"articleSection\":[\"Transformaci\u00f3n Digital\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/\",\"name\":\"Dependencia tecnol\u00f3gica positiva | Suplos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulo-Portada.png\",\"datePublished\":\"2021-10-07T19:20:19+00:00\",\"dateModified\":\"2025-07-06T19:34:06+00:00\",\"description\":\"Un an\u00e1lisis sobre c\u00f3mo la tecnolog\u00eda ha generado un sinn\u00famero de debates sobre qu\u00e9 tan dependientes somos y hasta qu\u00e9 punto es negativo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulo-Portada.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulo-Portada.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/dependencia-tecnologica-positiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dependencia tecnol\u00f3gica positiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\",\"name\":\"Andres Sarmiento\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/en\\\/author\\\/asarmiento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Positive technology dependence","description":"An analysis of how technology has generated countless debates about how dependent we are and to what extent it is negative.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/en\/digital-transformation\/positive-technology-dependence\/","og_locale":"en_US","og_type":"article","og_title":"Dependencia tecnol\u00f3gica positiva | Suplos","og_description":"Un an\u00e1lisis sobre c\u00f3mo la tecnolog\u00eda ha generado un sinn\u00famero de debates sobre qu\u00e9 tan dependientes somos y hasta qu\u00e9 punto es negativo.","og_url":"https:\/\/suplos.com\/en\/digital-transformation\/positive-technology-dependence\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2021-10-07T19:20:19+00:00","article_modified_time":"2025-07-06T19:34:06+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/10\/Articulo-Portada.png","type":"image\/png"}],"author":"Andres Sarmiento","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andres Sarmiento","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/"},"author":{"name":"Andres Sarmiento","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897"},"headline":"Dependencia tecnol\u00f3gica positiva","datePublished":"2021-10-07T19:20:19+00:00","dateModified":"2025-07-06T19:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/"},"wordCount":530,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/10\/Articulo-Portada.png","articleSection":["Transformaci\u00f3n Digital"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/","url":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/","name":"Positive technology dependence","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/10\/Articulo-Portada.png","datePublished":"2021-10-07T19:20:19+00:00","dateModified":"2025-07-06T19:34:06+00:00","description":"An analysis of how technology has generated countless debates about how dependent we are and to what extent it is negative.","breadcrumb":{"@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/10\/Articulo-Portada.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/10\/Articulo-Portada.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/transformacion-digital\/dependencia-tecnologica-positiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Dependencia tecnol\u00f3gica positiva"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Procurement Management Software","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897","name":"Andres Sarmiento","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/en\/author\/asarmiento\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/comments?post=1872"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1872\/revisions"}],"predecessor-version":[{"id":16963,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1872\/revisions\/16963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media\/16962"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media?parent=1872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/categories?post=1872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/tags?post=1872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}