{"id":1910,"date":"2021-11-11T16:28:10","date_gmt":"2021-11-11T16:28:10","guid":{"rendered":"https:\/\/suplos.com\/?p=1910"},"modified":"2025-07-06T14:29:32","modified_gmt":"2025-07-06T19:29:32","slug":"claves-conocer-contraparte","status":"publish","type":"post","link":"https:\/\/suplos.com\/en\/gestion-de-abastecimiento\/claves-conocer-contraparte\/","title":{"rendered":"5 keys to know your counterparty and its end beneficiary"},"content":{"rendered":"<p>La contraparte es cualquier persona natural o jur\u00eddica con la que la <strong>empresa tenga v\u00ednculos comerciales, de negocios, contractuales o jur\u00eddicos de cualquier orden.<\/strong> Entre otros, son contrapartes los asociados, empleados, clientes, contratistas y proveedores de productos de la empresa.<\/p>\n\n\n\n<p>Es importante conocer qui\u00e9n es tu contraparte; esto lo puedes realizar por medio de la solicitud de documentos para validar su informaci\u00f3n b\u00e1sica, financiera y t\u00e9cnica. <strong>Adem\u00e1s, puedes conocer qui\u00e9nes son sus representantes legales, accionistas y beneficiarios finales.<\/strong><\/p>\n\n\n\n<p>Puedes complementar el conocimiento obtenido de los documentos solicitados, realizando tambi\u00e9n una visita en campo a sus instalaciones o establecimiento de comercio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es un beneficiario final o real?<\/strong><\/h2>\n\n\n\n<p>Se entiende por beneficiario real la(s) persona(s) natural(es) que finalmente posee(n) o controla(n) a un cliente o la persona natural en cuyo nombre se realiza una transacci\u00f3n. <strong>Incluye tambi\u00e9n a la(s) persona(s) que ejerzan el control efectivo y\/o final, directa o indirectamente<\/strong>, sobre una persona jur\u00eddica u otra estructura sin personer\u00eda jur\u00eddica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Aspectos claves para tener en cuenta<\/strong><\/h3>\n\n\n\n<p>A) Identificar al beneficiario final de tu contraparte, tomar las medidas pertinentes para verificar su identidad.<\/p>\n\n\n\n<p>B) Realizar debidas diligencias con la informaci\u00f3n obtenida en la documentaci\u00f3n solicitada, validaci\u00f3n de listas restrictivas a cada uno de los miembros que conforman la empresa.<\/p>\n\n\n\n<p>C) Pa\u00edses de riesgo alto y medio: Validar si el tercero, la cuenta bancaria, el receptor de pago o su cuenta bancaria se encuentran en jurisdicciones de riesgo alto o medio.<\/p>\n\n\n\n<p>D) Contar con mecanismos que permitan consolidar e identificar alertas presentes o futuras, contar con fecha del proceso de conocimiento o monitoreo de la contraparte.<\/p>\n\n\n\n<p>E) Ejercer un especial control para mantener la informaci\u00f3n y documentaci\u00f3n actualizada, en el caso que alguna contraparte no actualice la informaci\u00f3n, este hecho debe ser analizado como una \u201cse\u00f1al de alerta\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Algunas se\u00f1ales de alerta<\/strong><\/h3>\n\n\n\n<p>A) Contrapartes que <strong>realizan operaciones en cantidades o valores no acordes<\/strong> a su actividad econ\u00f3mica.<\/p>\n\n\n\n<p>B) Contrapartes que <strong>ofrecen productos o servicios con precios por debajo<\/strong> de los costos normales del mercado.<\/p>\n\n\n\n<p>C)Contrapartes que <strong>presentan inconsistencias en la informaci\u00f3n relacionada<\/strong> vs la documentada.<\/p>\n\n\n\n<p>D) Socios, accionistas, representantes que cuenten con <strong>antecedentes judiciales LA\/FT\/FPADM<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo la tecnolog\u00eda ayuda a las empresas a conocer sus contrapartes?<\/strong><\/h2>\n\n\n\n<p>En el mercado se pueden encontrar plataformas como Suplos en la que puedes registrar a todos los terceros, acreedores, contratistas con los que se tiene o se puede llegar a tener una relaci\u00f3n comercial, obtener su informaci\u00f3n y documentaci\u00f3n b\u00e1sica, t\u00e9cnica y financiera, actualizarla anualmente, validar en listas restrictivas a sus representantes, accionistas, beneficiario final, mantener un control de las alertas generadas. Dentro de las listas que se validan se encuentran: nacionales, internacionales, PEPS, noticias, entre otras.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sources:<\/strong><\/h4>\n\n\n\n<p>Circular externa 100-00004 Superintendencia de sociedades<\/p>\n\n\n\n<p>Circular externa 100-000016 Superintendencia de sociedades<\/p>","protected":false},"excerpt":{"rendered":"<p>La contraparte es cualquier persona natural o jur\u00eddica con la que la empresa tenga v\u00ednculos comerciales, de negocios, contractuales o jur\u00eddicos de cualquier orden. Entre otros, son contrapartes los asociados, empleados, clientes, contratistas y proveedores de productos de la empresa. Es importante conocer qui\u00e9n es tu contraparte; esto lo puedes realizar por medio de la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":16949,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-1910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 claves para conocer tu contraparte y su beneficiario final<\/title>\n<meta name=\"description\" content=\"La contraparte es cualquier persona natural o jur\u00eddica con la que la empresa tenga v\u00ednculos comerciales, de negocios o jur\u00eddicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/en\/supply-management\/claves-conocer-contraparte\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 claves para conocer tu contraparte y su beneficiario final\" \/>\n<meta property=\"og:description\" content=\"La contraparte es cualquier persona natural o jur\u00eddica con la que la empresa tenga v\u00ednculos comerciales, de negocios o jur\u00eddicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/en\/supply-management\/claves-conocer-contraparte\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T16:28:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T19:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gina Visbal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gina Visbal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/\"},\"author\":{\"name\":\"Gina Visbal\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/9d0acc4db9a5646b59f0d6d877f13784\"},\"headline\":\"5 claves para conocer tu contraparte y su beneficiario final\",\"datePublished\":\"2021-11-11T16:28:10+00:00\",\"dateModified\":\"2025-07-06T19:29:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/\"},\"wordCount\":506,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-1.png\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/\",\"name\":\"5 claves para conocer tu contraparte y su beneficiario final\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-1.png\",\"datePublished\":\"2021-11-11T16:28:10+00:00\",\"dateModified\":\"2025-07-06T19:29:32+00:00\",\"description\":\"La contraparte es cualquier persona natural o jur\u00eddica con la que la empresa tenga v\u00ednculos comerciales, de negocios o jur\u00eddicos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-1.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-1.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/claves-conocer-contraparte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 claves para conocer tu contraparte y su beneficiario final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/9d0acc4db9a5646b59f0d6d877f13784\",\"name\":\"Gina Visbal\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/en\\\/author\\\/gvisbal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 keys to know your counterparty and its end beneficiary","description":"La contraparte es cualquier persona natural o jur\u00eddica con la que la empresa tenga v\u00ednculos comerciales, de negocios o jur\u00eddicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/en\/supply-management\/claves-conocer-contraparte\/","og_locale":"en_US","og_type":"article","og_title":"5 claves para conocer tu contraparte y su beneficiario final","og_description":"La contraparte es cualquier persona natural o jur\u00eddica con la que la empresa tenga v\u00ednculos comerciales, de negocios o jur\u00eddicos.","og_url":"https:\/\/suplos.com\/en\/supply-management\/claves-conocer-contraparte\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2021-11-11T16:28:10+00:00","article_modified_time":"2025-07-06T19:29:32+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-1.png","type":"image\/png"}],"author":"Gina Visbal","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gina Visbal","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/"},"author":{"name":"Gina Visbal","@id":"https:\/\/suplos.com\/#\/schema\/person\/9d0acc4db9a5646b59f0d6d877f13784"},"headline":"5 claves para conocer tu contraparte y su beneficiario final","datePublished":"2021-11-11T16:28:10+00:00","dateModified":"2025-07-06T19:29:32+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/"},"wordCount":506,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-1.png","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/","name":"5 keys to know your counterparty and its end beneficiary","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-1.png","datePublished":"2021-11-11T16:28:10+00:00","dateModified":"2025-07-06T19:29:32+00:00","description":"La contraparte es cualquier persona natural o jur\u00eddica con la que la empresa tenga v\u00ednculos comerciales, de negocios o jur\u00eddicos.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-1.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-1.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/claves-conocer-contraparte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"5 claves para conocer tu contraparte y su beneficiario final"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Procurement Management Software","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/9d0acc4db9a5646b59f0d6d877f13784","name":"Gina Visbal","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/en\/author\/gvisbal\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/comments?post=1910"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1910\/revisions"}],"predecessor-version":[{"id":16955,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/1910\/revisions\/16955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media\/16949"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media?parent=1910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/categories?post=1910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/tags?post=1910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}