{"id":3304,"date":"2023-04-21T12:16:14","date_gmt":"2023-04-21T17:16:14","guid":{"rendered":"https:\/\/suplos.com\/?p=3304"},"modified":"2025-07-06T11:11:35","modified_gmt":"2025-07-06T16:11:35","slug":"supply-chain-data-analysis","status":"publish","type":"post","link":"https:\/\/suplos.com\/en\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/","title":{"rendered":"<strong>How does data analysis work in the Supply Chain?<\/strong>\u00a0"},"content":{"rendered":"<p>El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas, esto se debe a que la Cadena de Suministro suele generar grandes vol\u00famenes de datos que son relevantes y confiables.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPor qu\u00e9 es importante utilizar el an\u00e1lisis de datos en la Cadena de Suministro?&nbsp;<\/h2>\n\n\n\n<p>La Cadena de Suministro re\u00fane todos los datos necesarios que se generan durante los diferentes procesos. Estos datos pueden ser esenciales para ayudar a los l\u00edderes empresariales a mejorar la eficiencia, trazabilidad y operaci\u00f3n en distintas fases. A continuaci\u00f3n, te compartimos algunos beneficios:&nbsp;<\/p>\n\n\n<h3>Comprender los riesgos<\/h3>\n\n\n<p>Al realizar un correcto an\u00e1lisis de datos se logran identificar los riesgos que se pueden presentar en un futuro en la empresa, esto se obtiene mediante la detecci\u00f3n de patrones y tendencias en toda la Cadena.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Precisi\u00f3n en la planificaci\u00f3n<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Al analizar los datos de los clientes y de la Cadena de Suministro se puede llegar a identificar mejor la demanda futura de la empresa. As\u00ed mismo ayuda a que las organizaciones decidan cuales son los productos que son m\u00e1s rentables y satisfacer las necesidades de los clientes.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Obtener una Cadena de Suministro ajustada<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Las empresas pueden utilizar el an\u00e1lisis de datos de la Cadena de Suministro para supervisar el almac\u00e9n, las respuestas de los proveedores y las necesidades de los clientes para tomar decisiones mejor informadas.&nbsp;<\/p>\n\n\n\n<p>La anal\u00edtica avanzada procesa datos m\u00e1s estructurados los cuales brindan a las empresas una ventaja competitiva en el mercado, debido a que se aseguran de que las alertas de posibles riesgos lleguen a tiempo y tomen decisiones m\u00e1s optimas. Hay que tener en cuenta que existen diferentes tipos de an\u00e1lisis de datos para la Cadena de Suministro, estos son:&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anal\u00edtica descriptiva<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Proporciona mayor visibilidad de informaci\u00f3n en toda la Cadena de Suministro, tanto para sistemas y datos internos como externos.&nbsp;<br>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anal\u00edtica predictiva<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Ayuda a las empresas a comprender las proyecciones para el futuro y sus implicaciones para la empresa. Esto permite una mayor visibilidad del historial de todos los datos que se han ido generando y de esta manera prevenir riesgos futuros.&nbsp;<br>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anal\u00edtica prescriptiva<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Esta ayuda a que las organizaciones puedan resolver los problemas que se presentan y colaborar para obtener un mayor valor empresarial. &nbsp;<br>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anal\u00edtica cognitiva<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Las empresas podr\u00e1n responder preguntas o problemas complejos al implementar tecnolog\u00edas las cuales ayuden a optimizar y mejorar la Cadena de Suministro.&nbsp;<\/p>\n\n\n\n<p>Por esto, muchas empresas deciden implementar el an\u00e1lisis de datos en su Cadena de Suministros, en cuanto mejor se ejecute la anal\u00edtica mejor ser\u00e1n las decisiones que tome la empresa generando as\u00ed mayor valor en el mercado y obteniendo una sustentabilidad a largo plazo.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas, esto se debe a que la Cadena de Suministro suele generar grandes vol\u00famenes de datos que son relevantes y confiables.&nbsp; \u00bfPor qu\u00e9 es importante utilizar el an\u00e1lisis de datos en la Cadena de Suministro?&nbsp; [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":16880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-3304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo es el an\u00e1lisis de datos en la Cadena de Suministro?<\/title>\n<meta name=\"description\" content=\"El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/en\/supply-management\/supply-chain-data-analysis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo es el an\u00e1lisis de datos en la Cadena de Suministro?\" \/>\n<meta property=\"og:description\" content=\"El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/en\/supply-management\/supply-chain-data-analysis\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-21T17:16:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T16:11:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2023\/04\/Articulo-portada-1-unsmushed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brayan Aguilar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brayan Aguilar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/\"},\"author\":{\"name\":\"Brayan Aguilar\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/ec2c3590b1ff5070adca805e8ac72743\"},\"headline\":\"\u00bfC\u00f3mo funciona el an\u00e1lisis de datos en la Cadena de Suministro?\u00a0\",\"datePublished\":\"2023-04-21T17:16:14+00:00\",\"dateModified\":\"2025-07-06T16:11:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/\"},\"wordCount\":504,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Articulo-portada-1-unsmushed.jpg\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/\",\"name\":\"\u00bfC\u00f3mo es el an\u00e1lisis de datos en la Cadena de Suministro?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Articulo-portada-1-unsmushed.jpg\",\"datePublished\":\"2023-04-21T17:16:14+00:00\",\"dateModified\":\"2025-07-06T16:11:35+00:00\",\"description\":\"El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Articulo-portada-1-unsmushed.jpg\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Articulo-portada-1-unsmushed.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/analisis-de-datos-en-la-cadena-de-suministro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo funciona el an\u00e1lisis de datos en la Cadena de Suministro?\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/ec2c3590b1ff5070adca805e8ac72743\",\"name\":\"Brayan Aguilar\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/en\\\/author\\\/baguilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo es el an\u00e1lisis de datos en la Cadena de Suministro?","description":"El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/en\/supply-management\/supply-chain-data-analysis\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfC\u00f3mo es el an\u00e1lisis de datos en la Cadena de Suministro?","og_description":"El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas.","og_url":"https:\/\/suplos.com\/en\/supply-management\/supply-chain-data-analysis\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2023-04-21T17:16:14+00:00","article_modified_time":"2025-07-06T16:11:35+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/04\/Articulo-portada-1-unsmushed.jpg","type":"image\/jpeg"}],"author":"Brayan Aguilar","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Brayan Aguilar","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/"},"author":{"name":"Brayan Aguilar","@id":"https:\/\/suplos.com\/#\/schema\/person\/ec2c3590b1ff5070adca805e8ac72743"},"headline":"\u00bfC\u00f3mo funciona el an\u00e1lisis de datos en la Cadena de Suministro?\u00a0","datePublished":"2023-04-21T17:16:14+00:00","dateModified":"2025-07-06T16:11:35+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/"},"wordCount":504,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/04\/Articulo-portada-1-unsmushed.jpg","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/","name":"\u00bfC\u00f3mo es el an\u00e1lisis de datos en la Cadena de Suministro?","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/04\/Articulo-portada-1-unsmushed.jpg","datePublished":"2023-04-21T17:16:14+00:00","dateModified":"2025-07-06T16:11:35+00:00","description":"El an\u00e1lisis de datos puede ser una de las soluciones m\u00e1s \u00fatiles a la hora de tomar decisiones para las empresas.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/04\/Articulo-portada-1-unsmushed.jpg","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/04\/Articulo-portada-1-unsmushed.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/analisis-de-datos-en-la-cadena-de-suministro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo funciona el an\u00e1lisis de datos en la Cadena de Suministro?\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Procurement Management Software","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/ec2c3590b1ff5070adca805e8ac72743","name":"Brayan Aguilar","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/en\/author\/baguilar\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/3304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/comments?post=3304"}],"version-history":[{"count":1,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/3304\/revisions"}],"predecessor-version":[{"id":16172,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/3304\/revisions\/16172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media\/16880"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media?parent=3304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/categories?post=3304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/tags?post=3304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}