{"id":830,"date":"2020-07-23T21:58:00","date_gmt":"2020-07-23T21:58:00","guid":{"rendered":"https:\/\/suplos.com\/?p=830"},"modified":"2025-07-14T14:48:58","modified_gmt":"2025-07-14T19:48:58","slug":"departamentos-de-compras","status":"publish","type":"post","link":"https:\/\/suplos.com\/en\/soluciones-financieras\/departamentos-de-compras\/","title":{"rendered":"Part 2: Metrics that show the most important changes in purchasing departments"},"content":{"rendered":"<p>A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras de grandes empresas y c\u00f3mo su funci\u00f3n ha tenido cambios significativos, que se esperan sean permanentes.<\/p>\n\n\n\n<p>En las siguientes m\u00e9tricas se exploran los cambios m\u00e1s relevantes en la funci\u00f3n de Compras, resaltando las estrategias con mayor adopci\u00f3n y el acompa\u00f1amiento de la tecnolog\u00eda en el proceso.\u00a0<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2020\/10\/infografia-blog-02-860x1536-1-573x1024.jpg\" alt=\"\" class=\"wp-image-831\" style=\"width:463px;height:825px\"\/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras de grandes empresas y c\u00f3mo su funci\u00f3n ha tenido cambios significativos, que se esperan sean permanentes. En las siguientes m\u00e9tricas se exploran los cambios m\u00e1s relevantes en la funci\u00f3n de Compras, resaltando las estrategias con mayor [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17507,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soluciones-financieras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambios en los departamentos de compras | Suplos<\/title>\n<meta name=\"description\" content=\"A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/en\/financial-solutions\/departamentos-de-compras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambios en los departamentos de compras | Suplos\" \/>\n<meta property=\"og:description\" content=\"A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/en\/financial-solutions\/departamentos-de-compras\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-23T21:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T19:48:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2020\/07\/metricas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tatiana Calero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tatiana Calero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/\"},\"author\":{\"name\":\"Tatiana Calero\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/94dedd93b3d634d7b59f4e5299e6bb26\"},\"headline\":\"Segunda parte: Las m\u00e9tricas que muestran los cambios m\u00e1s importantes en los departamentos de Compras\",\"datePublished\":\"2020-07-23T21:58:00+00:00\",\"dateModified\":\"2025-07-14T19:48:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/\"},\"wordCount\":93,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/metricas.png\",\"articleSection\":[\"Soluciones financieras\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/\",\"name\":\"Cambios en los departamentos de compras | Suplos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/metricas.png\",\"datePublished\":\"2020-07-23T21:58:00+00:00\",\"dateModified\":\"2025-07-14T19:48:58+00:00\",\"description\":\"A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/metricas.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/metricas.png\",\"width\":1920,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/departamentos-de-compras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segunda parte: Las m\u00e9tricas que muestran los cambios m\u00e1s importantes en los departamentos de Compras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/94dedd93b3d634d7b59f4e5299e6bb26\",\"name\":\"Tatiana Calero\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/en\\\/author\\\/tatiana-calero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambios en los departamentos de compras | Suplos","description":"A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/en\/financial-solutions\/departamentos-de-compras\/","og_locale":"en_US","og_type":"article","og_title":"Cambios en los departamentos de compras | Suplos","og_description":"A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras.","og_url":"https:\/\/suplos.com\/en\/financial-solutions\/departamentos-de-compras\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2020-07-23T21:58:00+00:00","article_modified_time":"2025-07-14T19:48:58+00:00","og_image":[{"width":1920,"height":650,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/07\/metricas.png","type":"image\/png"}],"author":"Tatiana Calero","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tatiana Calero","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/"},"author":{"name":"Tatiana Calero","@id":"https:\/\/suplos.com\/#\/schema\/person\/94dedd93b3d634d7b59f4e5299e6bb26"},"headline":"Segunda parte: Las m\u00e9tricas que muestran los cambios m\u00e1s importantes en los departamentos de Compras","datePublished":"2020-07-23T21:58:00+00:00","dateModified":"2025-07-14T19:48:58+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/"},"wordCount":93,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/07\/metricas.png","articleSection":["Soluciones financieras"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/","url":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/","name":"Cambios en los departamentos de compras | Suplos","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/07\/metricas.png","datePublished":"2020-07-23T21:58:00+00:00","dateModified":"2025-07-14T19:48:58+00:00","description":"A trav\u00e9s de la siguiente infograf\u00eda queremos mostrar los cambios m\u00e1s importantes que han tenido los Directores de Compras.","breadcrumb":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/07\/metricas.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/07\/metricas.png","width":1920,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/soluciones-financieras\/departamentos-de-compras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Segunda parte: Las m\u00e9tricas que muestran los cambios m\u00e1s importantes en los departamentos de Compras"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Procurement Management Software","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/94dedd93b3d634d7b59f4e5299e6bb26","name":"Tatiana Calero","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/en\/author\/tatiana-calero\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/comments?post=830"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/830\/revisions"}],"predecessor-version":[{"id":17758,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/posts\/830\/revisions\/17758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media\/17507"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/media?parent=830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/categories?post=830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/en\/wp-json\/wp\/v2\/tags?post=830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}