{"id":16033,"date":"2022-02-03T10:30:00","date_gmt":"2022-02-03T10:30:00","guid":{"rendered":"https:\/\/suplos.com\/?p=2305"},"modified":"2025-07-06T14:20:19","modified_gmt":"2025-07-06T19:20:19","slug":"scrum-gestion-equipos","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/gestion-de-abastecimiento\/scrum-gestion-equipos\/","title":{"rendered":"Scrum: das origens do r\u00fagbi ao gerenciamento de equipes"},"content":{"rendered":"<p>El rugby, cuyo origen se remonta a 1823 por el ingl\u00e9s William Webb Ellis en la Rugby School, es el deporte que inspir\u00f3 a su vez el origen a la metodolog\u00eda del agilismo denominada \u201cscrum\u201d, esta corresponde a una formaci\u00f3n espec\u00edfica dentro del juego donde los delanteros (8 en total de cada equipo, denominado com\u00fanmente como <em>pack de forwards<\/em>) disputan la pelota ovalada posterior a una infracci\u00f3n menor; en Argentina, la \u00fanica potencia de Latinoam\u00e9rica hasta el momento en rugby, a esta formaci\u00f3n la denominan \u201cmel\u00e9\u201d.&nbsp;<\/p>\n\n\n\n<p>La inspiraci\u00f3n y relaci\u00f3n con la metodolog\u00eda no es menor, dada la naturaleza de\u202f<strong>trabajo colaborativo, autorregulaci\u00f3n, aprendizaje continuo, capacidad de reacci\u00f3n ante cambios del entorno, apoyo incondicional<\/strong>\u202fy otros elementos en general del deporte y la metodolog\u00eda que logran una estrecha relaci\u00f3n en t\u00e9rminos generales.&nbsp;<\/p>\n\n\n\n<p>Cada persona que participa en la formaci\u00f3n tiene una\u202f<strong>funci\u00f3n y un rol espec\u00edfico <\/strong>que cumplen a cabalidad para lograr un\u202f<strong>objetivo \u00fanico y com\u00fan.\u202f<\/strong>En el caso del rugby es lograr obtener la posesi\u00f3n de pelota; en la primera hilera se ubica un <em>hooker<\/em> (#2) quien es el encargado de ganar la posesi\u00f3n del bal\u00f3n con su tal\u00f3n y est\u00e1 apoyado entre dos pilares (#1 y #3) quienes cumplen la funci\u00f3n de empujar, en la segunda hilera se ubican justo entre los pilares y el hooker, los segundas l\u00edneas (#4 y #5), quienes fijan la posici\u00f3n y ejercen el empuje principal y a sus costados las \u201calas\u201d (#6 y #7) quienes estabilizan la formaci\u00f3n y deben estar listos para librarse en caso de p\u00e9rdida de la formaci\u00f3n y finalmente, en la tercera hilera se ubica el jugador n\u00famero 8 (#8) quien se encarga de empujar y mantener la posici\u00f3n del bal\u00f3n en caso de ir ganando la formaci\u00f3n hasta que considere necesario. Esta descripci\u00f3n de\u202f<strong>empuje constante para cumplir el objetivo<\/strong>, pero con detalle de tareas espec\u00edficas, es justamente la naturaleza del <em>scrum team<\/em>, mediante las responsabilidades espec\u00edficas de <em>los developers, scrum master<\/em> y <em>product owner<\/em> buscan lograr el objetivo.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/02\/Rugby.png\" alt=\"\" class=\"wp-image-2307\"\/><\/figure>\n<\/div>\n\n\n<p>Dentro de los pilares de la metodolog\u00eda est\u00e1n la\u202f<strong>transparencia, inspecci\u00f3n y adaptaci\u00f3n<\/strong>, en el deporte la formaci\u00f3n de scrum tiene un\u202f<strong>entorno altamente cambiante<\/strong>\u202fya que en cada oportunidad el adversario puede\u202f<strong>cambiar su estrategia<\/strong>, empujes cortos y constantes, empujes con frecuencias separadas pero con mayor intensidad, giro de la formaci\u00f3n a trav\u00e9s de presi\u00f3n espec\u00edfica de sus alas, entre otros, lo que implica en el grupo de delanteros del equipo,\u202f<strong>mantener una comunicaci\u00f3n constante<\/strong>\u202fde la evoluci\u00f3n de la formaci\u00f3n, de tal forma que el resto de jugadores del equipo (7 en total de cada equipo, denominado com\u00fanmente como l\u00edneas) se puedan posicionar en ataque o en defensa y puedan con el resultado de la formaci\u00f3n tomar una decisi\u00f3n. Cada segundo, cada movimiento en la formaci\u00f3n <strong>implica una adaptaci\u00f3n de cada funci\u00f3n<\/strong>\u202fpara continuar con la b\u00fasqueda del objetivo y cada miembro al sentir el avance o retroceso debe\u202f<strong>autogestionarse dentro de su posici\u00f3n<\/strong>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Valores de la metodolog\u00eda Scrum<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Los valores de la metodolog\u00eda scrum est\u00e1n no solo en la formaci\u00f3n de juego (rugby) sino en general en todo el juego.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O<strong>respeto<\/strong>\u202fes el de mayor valor en el juego, \u201cjuego de villanos, jugado por caballeros\u201d a pesar de tener tanto contacto f\u00edsico, el respeto por el adversario, el compa\u00f1ero y el \u00e1rbitro es absoluto, dif\u00edcilmente se visualiza un jugador de rugby discutiendo una decisi\u00f3n arbitral y en caso de ocurrir, el juez puede determinar p\u00e9rdida de campo propio de cinco metros cada que existan comentarios de los jugadores.&nbsp;<\/li>\n\n\n\n<li>O<strong>compromiso<\/strong>\u202fes algo invaluable en el rugby, inclusive puede declararse un jugador como el mejor de la cancha sin haber tocado el bal\u00f3n durante todo el partido. El apoyo, el empuje, la presencia en la cancha pueden\u202f<strong>hacer la diferencia a la hora de conseguir los objetivos<\/strong>.&nbsp;<\/li>\n\n\n\n<li>O<strong>coraje<\/strong>\u202fante las dificultades que se puedan presentar durante el juego como tener un adversario de marca que te gana en velocidad y fuerza,\u202f<strong>plantear diversas alternativas del equipo<\/strong>\u202fa la hora de contener en defensa con\u202f<strong>virajes r\u00e1pidos<\/strong>\u202f<strong>que permitan la mejora constante<\/strong>\u202fdurante el desarrollo del juego.&nbsp;<\/li>\n\n\n\n<li>Los cambios de jugadores en el rugby ocurren generalmente por lesiones o cansancio, dif\u00edcilmente un jugador de rugby por motivado que est\u00e9 en el juego al ser sustituido muestra su molestia con los entrenadores, se realiza la\u202f<strong>conciencia que las decisiones que se toman hacen parte de una mejor opci\u00f3n para el equipo<\/strong>, demostrando\u202f<strong>franqueza y transparencia<\/strong>.<\/li>\n\n\n\n<li>Finalmente, el\u202f<strong>foco<\/strong>\u202fen el objetivo es clave para cada uno de los quince jugadores del rugby en cada posici\u00f3n, conocer que en caso de alguna falla se debe\u202f<strong>corregir sobre la marcha<\/strong>, que no es necesario recibir instrucciones constantes, el entrenador de rugby est\u00e1 normalmente en la tribuna observando desde una posici\u00f3n perif\u00e9rica el juego, la preparaci\u00f3n y planeaci\u00f3n previa del juego de la semana hacen del jugador pueda\u202f<strong>tomar decisiones y apoyar a sus compa\u00f1eros<\/strong>\u202fy conseguir un \u00a1try!&nbsp;<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>El rugby, cuyo origen se remonta a 1823 por el ingl\u00e9s William Webb Ellis en la Rugby School, es el deporte que inspir\u00f3 a su vez el origen a la metodolog\u00eda del agilismo denominada \u201cscrum\u201d, esta corresponde a una formaci\u00f3n espec\u00edfica dentro del juego donde los delanteros (8 en total de cada equipo, denominado com\u00fanmente [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":16939,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-16033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scrum: del rugby, a la gesti\u00f3n de equipos<\/title>\n<meta name=\"description\" content=\"La metodolog\u00eda scrum como responsabilidades espec\u00edficas de los developers, scrum master y product owner buscan lograr el objetivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/scrum-gestion-equipos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scrum: del rugby, a la gesti\u00f3n de equipos\" \/>\n<meta property=\"og:description\" content=\"La metodolog\u00eda scrum como responsabilidades espec\u00edficas de los developers, scrum master y product owner buscan lograr el objetivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/scrum-gestion-equipos\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T10:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T19:20:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/02\/Articulo-Portada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julian Toro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julian Toro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/\"},\"author\":{\"name\":\"Julian Toro\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/548da986b9c5198bba74ab21b97f53b7\"},\"headline\":\"Scrum: del origen en el rugby, a la gesti\u00f3n de equipos\",\"datePublished\":\"2022-02-03T10:30:00+00:00\",\"dateModified\":\"2025-07-06T19:20:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/\"},\"wordCount\":908,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Articulo-Portada.png\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/\",\"name\":\"Scrum: del rugby, a la gesti\u00f3n de equipos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Articulo-Portada.png\",\"datePublished\":\"2022-02-03T10:30:00+00:00\",\"dateModified\":\"2025-07-06T19:20:19+00:00\",\"description\":\"La metodolog\u00eda scrum como responsabilidades espec\u00edficas de los developers, scrum master y product owner buscan lograr el objetivo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Articulo-Portada.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Articulo-Portada.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/scrum-gestion-equipos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scrum: del origen en el rugby, a la gesti\u00f3n de equipos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/548da986b9c5198bba74ab21b97f53b7\",\"name\":\"Julian Toro\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/jtoro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scrum: del rugby, a la gesti\u00f3n de equipos","description":"La metodolog\u00eda scrum como responsabilidades espec\u00edficas de los developers, scrum master y product owner buscan lograr el objetivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/scrum-gestion-equipos\/","og_locale":"pt_BR","og_type":"article","og_title":"Scrum: del rugby, a la gesti\u00f3n de equipos","og_description":"La metodolog\u00eda scrum como responsabilidades espec\u00edficas de los developers, scrum master y product owner buscan lograr el objetivo.","og_url":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/scrum-gestion-equipos\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2022-02-03T10:30:00+00:00","article_modified_time":"2025-07-06T19:20:19+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/02\/Articulo-Portada.png","type":"image\/png"}],"author":"Julian Toro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julian Toro","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/"},"author":{"name":"Julian Toro","@id":"https:\/\/suplos.com\/#\/schema\/person\/548da986b9c5198bba74ab21b97f53b7"},"headline":"Scrum: del origen en el rugby, a la gesti\u00f3n de equipos","datePublished":"2022-02-03T10:30:00+00:00","dateModified":"2025-07-06T19:20:19+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/"},"wordCount":908,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/02\/Articulo-Portada.png","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/","name":"Scrum: del rugby, a la gesti\u00f3n de equipos","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/02\/Articulo-Portada.png","datePublished":"2022-02-03T10:30:00+00:00","dateModified":"2025-07-06T19:20:19+00:00","description":"La metodolog\u00eda scrum como responsabilidades espec\u00edficas de los developers, scrum master y product owner buscan lograr el objetivo.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/02\/Articulo-Portada.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/02\/Articulo-Portada.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/scrum-gestion-equipos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Scrum: del origen en el rugby, a la gesti\u00f3n de equipos"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/548da986b9c5198bba74ab21b97f53b7","name":"Julian Toro","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/jtoro\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/16033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=16033"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/16033\/revisions"}],"predecessor-version":[{"id":16941,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/16033\/revisions\/16941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/16939"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=16033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=16033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=16033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}