{"id":16034,"date":"2022-08-11T09:50:56","date_gmt":"2022-08-11T14:50:56","guid":{"rendered":"https:\/\/suplos.com\/?p=2791"},"modified":"2025-07-06T13:07:23","modified_gmt":"2025-07-06T18:07:23","slug":"tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/","title":{"rendered":"Nos bastidores do lan\u00e7amento de projetos de tecnologia ao vivo"},"content":{"rendered":"<p>Quienes han trabajado en proyectos conocen de primera mano esa <strong>sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo<\/strong>. La comunicaci\u00f3n por parte del l\u00edder confirmando que el proyecto ha entrado en operaci\u00f3n, genera una gran satisfacci\u00f3n y a la vez un gran temor, dado que detr\u00e1s de esas tres l\u00edneas del correo, existi\u00f3 una programaci\u00f3n, dise\u00f1o, expectativa, conocimiento del equipo de trabajo, imprevistos, planes de acci\u00f3n para solucionar problemas, cambios de recursos, discusiones, nuevos interlocutores, trasnochos, toma de decisiones, en fin, la lista es interminable.<\/p>\n\n\n\n<p>Los proyectos de tecnolog\u00eda en particular tienen ciertos componentes adicionales que le agregan mucha m\u00e1s \u201cemoci\u00f3n\u201d a poder tener un proyecto no solo en vivo, sino estabilizado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Etapas de una salida en vivo<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa preliminar<\/strong><\/h3>\n\n\n\n<p>El primer ingrediente es que cuando se plantea la necesidad de iniciar un proyecto, el promotor supone mapas mentales donde toda la necesidad est\u00e1 clara y la fase de dise\u00f1o la da por finalizada sin dar inicio. <strong>La mayor\u00eda de las veces parten de esquemas o bocetos que carecen de todo nivel de detalle.<\/strong><\/p>\n\n\n\n<p>La mayor\u00eda de las veces <strong>el inicio del proyecto de tecnolog\u00eda no tiene nada que ver con tecnolog\u00eda<\/strong> y surgen diferentes necesidades en cuanto a reformar los procesos y evaluar la idoneidad de las personas del equipo que ejecutan las acciones que se van a ver impactadas con la implementaci\u00f3n de la herramienta tecnol\u00f3gica.<\/p>\n\n\n\n<p>En esta etapa preliminar aparecen las primeras fricciones dado que los tiempos de la necesidad ya inician atrasados&nbsp; pues no se hab\u00eda logrado convencer a los patrocinadores de invertir en una soluci\u00f3n de tecnolog\u00eda (<a href=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/como-vender-un-proyecto-de-tecnologia-dentro-de-la-organizacion-en-4-pasos\/\"><strong>aqu\u00ed algunos consejos para vender un proyecto de tecnolog\u00eda al interior de las compa\u00f1\u00edas de forma exitosa<\/strong><\/a>). El compromiso de los tiempos es un tema extremadamente delicado que genera bastantes frustraciones ya que <strong>lo normal es suponer tiempos sin tener clara ni la necesidad ni el nivel de esfuerzo<\/strong> y se basan en pr\u00e1cticas de proyectos diferentes a tecnolog\u00eda que no son comparables.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa de dise\u00f1o<\/strong><\/h3>\n\n\n\n<p>Suponiendo que esta etapa preliminar fue superada y se tom\u00f3 la decisi\u00f3n de disponer recursos para la ejecuci\u00f3n del proyecto, inicia en forma la etapa de dise\u00f1o funcional. <strong>En esta fase se deben plasmar todas esas ideas de gran nivel en un documento de detalle que, posteriormente, ser\u00e1 el insumo para que un equipo de desarrollo tecnol\u00f3gico pueda materializar la necesidad<\/strong>.<\/p>\n\n\n\n<p>Ese documento resulta ser un dolor de cabeza para los responsables funcionales ya que al unir al equipo que todos los d\u00edas ejecuta la tarea que ser\u00e1 digitalizada o automatizada, se tienen muchas aristas y se ejecutan diferentes criterios ya que depende finalmente de personas.<\/p>\n\n\n\n<p>Adicional, existen casu\u00edsticas que a pesar de ser la excepci\u00f3n son tratadas como una necesidad primaria a implementar que llevan a desarrollar <strong>l\u00f3gicas de alta complejidad sin el c\u00e1lculo de una medida de costo beneficio.<\/strong> Este proceso lleva bastantes iteraciones, es muy desgastante y suele ser la primera decepci\u00f3n del proyecto que debe ser controlada dado que los tiempos originales estimados ya fueron superados &nbsp;atendiendo una etapa de dise\u00f1o que desde la aprobaci\u00f3n deb\u00eda estar completada al 100%.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa de revisi\u00f3n t\u00e9cnica<\/strong><\/h3>\n\n\n\n<p>Posterior a esto viene una etapa de revisi\u00f3n t\u00e9cnica para aterrizar la necesidad funcional a l\u00f3gicas que se pueden lograr, la mayor\u00eda de las veces las necesidades funcionales son \u201cuna carta al ni\u00f1o Dios\u201d en las cuales la materializaci\u00f3n resulta bastante compleja y requiere recursos muy superiores a los estimados inicialmente debido a un bosquejo de gran nivel que no ten\u00eda el detalle necesario.<\/p>\n\n\n\n<p>Un componente adicional que le agrega complejidad a los proyectos tecnol\u00f3gicos es que se imaginan funcionalmente la integraci\u00f3n de diferentes herramientas tecnol\u00f3gicas, esto a pesar de ser realizable<strong>, la mayor\u00eda de las veces supone una coordinaci\u00f3n de diferentes interlocutores, proveedores tecnol\u00f3gicos con diferentes ANS, metodolog\u00edas de trabajo,prioridades, es una \u201ctorre de babel<\/strong>\u201d que requiere del mejor de los controles y rigurosidad por parte del responsable del proyecto como un todo.<\/p>\n\n\n\n<p>El problema de esta etapa no es solo poner de acuerdo a los equipos t\u00e9cnicos, sino poder transmitir al equipo funcional las restricciones de tecnolog\u00eda o los impactos del proyecto para ejecutar determinada funcionalidad. <strong>Al equipo funcional le genera bastante frustraci\u00f3n esta etapa dado que la premisa del proyecto original era cumplir una necesidad funcional y no cumplir la necesidad teniendo en cuentas las restricciones t\u00e9cnicas que no deber\u00edan de existir.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa de ejecuci\u00f3n de desarrollos<\/strong><\/h3>\n\n\n\n<p>Superadas todas las etapas, viene un aterrizaje de los tiempos y un cronograma de detalle para iniciar la ejecuci\u00f3n de los desarrollos; un tema relevante es que las etapas anteriores ya tuvieron un atraso con respecto a lo planeado originalmente y la disponibilidad de recursos puede haber cambiado de forma abrupta y <strong>lo primero ante esa liberaci\u00f3n es una fase de programaci\u00f3n de recursos y liberaci\u00f3n pertinente para atender el proyecto que, normalmente, no es considerado en el panorama de trabajo original.<\/strong><\/p>\n\n\n\n<p>Normalmente, los entregables de los proyectos de tecnolog\u00eda son binarios, no hay c\u00f3mo mostrar avances por la cantidad de componentes tecnol\u00f3gicos dependientes, enlazados e impactados, no es posible mostrar parte del flujo o la herramienta sin una integraci\u00f3n. <strong>Esta restricci\u00f3n es bastante dif\u00edcil de explicar y transmitir al equipo funcional<\/strong>, ya que los proyectos en otros \u00e1mbitos pueden verse el paso a paso e inclusive realizar correcciones a lo que se va viendo construido.<\/p>\n\n\n\n<p>En tecnolog\u00eda se desarrolla lo dise\u00f1ado, se prueba lo dise\u00f1ado y se entrega al cliente lo dise\u00f1ado, el cliente normalmente en esa entrega intenta involucrar nuevos actores que ser\u00e1n impactados con la salida del proyecto con el fin de realizar un manejo del cambio adecuado. <strong>Ac\u00e1 surgen nuevas necesidades, diferentes perspectivas, otras casu\u00edsticas que al no ser consideradas en el dise\u00f1o original impactan nuevamente el cronograma definido<\/strong>, la opci\u00f3n de cerrarse a cambios en esta etapa de primer contacto con los usuarios que van a operar la herramienta puede generar incomodidades y fricciones que perjudican en gran medida la aceptaci\u00f3n del proyecto.<\/p>\n\n\n\n<p>Una buena acci\u00f3n para controlar este tema es realizar un levantamiento de nuevos requerimientos en dos frentes: los que son totalmente necesarios para dar inicio al proyecto, \u201cstopper\u201d, y los que son deseables, pero no son necesarios y su implementaci\u00f3n mejorar\u00eda la experiencia, \u201cnice to have\u201d. <strong>Un tema relevante en este punto es ser bastante claros con el alcance definido y una expectativa en tiempo y recursos de poder abordar el 100% de las necesidades.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa de pruebas<\/strong><\/h3>\n\n\n\n<p>Una de las etapas m\u00e1s importantes de todo el proyecto es ejecutar <strong>pruebas de usuario funcional y dar una aprobaci\u00f3n formal<\/strong> de que lo desarrollado corresponde a lo pactado en las necesidades. Aqu\u00ed surgen impedimentos ya que el equipo dispuesto para esto no lo tiene como prioridad, dado que deben seguir atendiendo la operaci\u00f3n con las herramientas actuales. Es bastante importante, aunque se dificulta la mayor\u00eda de las veces, <strong>destinar tiempo de calidad para la ejecuci\u00f3n de pruebas a cabalidad para controlar al m\u00e1ximo los incidentes<\/strong> que puedan surgir en la operaci\u00f3n del proyecto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa de salida en vivo<\/strong><\/h3>\n\n\n\n<p>Todo lo anterior se materializa con el despliegue de las funcionalidades y <strong>salir a productivo para esto hay que tener mucho orden<\/strong> y disciplina para poder recopilar absolutamente toda la historia del recorrido del proyecto hasta este punto, cualquier olvido puede generar grandes insatisfacciones o se debe controlar con velocidad y proactividad. Posterior a eso viene toda una <strong>etapa de estabilizaci\u00f3n<\/strong> que debe tener atenci\u00f3n de primera l\u00ednea y poder generar el menor ruido posible ya que paralelo a la operaci\u00f3n del proyecto se est\u00e1n generando acciones de gesti\u00f3n de cambio para la recepci\u00f3n positiva y superar las barreras de entrada.<\/p>\n\n\n\n<p>Como puede verse, detr\u00e1s de las sacar proyectos de tecnolog\u00eda en vivo, \u00a1hay un mundo entero tras bambalinas!<\/p>","protected":false},"excerpt":{"rendered":"<p>Quienes han trabajado en proyectos conocen de primera mano esa sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo. La comunicaci\u00f3n por parte del l\u00edder confirmando que el proyecto ha entrado en operaci\u00f3n, genera una gran satisfacci\u00f3n y a la vez un gran temor, dado que detr\u00e1s de esas tres l\u00edneas del correo, existi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":16911,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-16034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda<\/title>\n<meta name=\"description\" content=\"Quienes han trabajado en proyectos conocen de primera mano esa sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"Quienes han trabajado en proyectos conocen de primera mano esa sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-11T14:50:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T18:07:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/08\/Articulo-portada-unsmushed.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julian Toro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julian Toro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/\"},\"author\":{\"name\":\"Julian Toro\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/548da986b9c5198bba74ab21b97f53b7\"},\"headline\":\"Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda\",\"datePublished\":\"2022-08-11T14:50:56+00:00\",\"dateModified\":\"2025-07-06T18:07:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/\"},\"wordCount\":1397,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Articulo-portada-unsmushed.png\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/\",\"name\":\"Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Articulo-portada-unsmushed.png\",\"datePublished\":\"2022-08-11T14:50:56+00:00\",\"dateModified\":\"2025-07-06T18:07:23+00:00\",\"description\":\"Quienes han trabajado en proyectos conocen de primera mano esa sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Articulo-portada-unsmushed.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Articulo-portada-unsmushed.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/548da986b9c5198bba74ab21b97f53b7\",\"name\":\"Julian Toro\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/jtoro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos bastidores do lan\u00e7amento de projetos de tecnologia ao vivo","description":"Quienes han trabajado en proyectos conocen de primera mano esa sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/","og_locale":"pt_BR","og_type":"article","og_title":"Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda","og_description":"Quienes han trabajado en proyectos conocen de primera mano esa sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo.","og_url":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2022-08-11T14:50:56+00:00","article_modified_time":"2025-07-06T18:07:23+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/08\/Articulo-portada-unsmushed.png","type":"image\/png"}],"author":"Julian Toro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julian Toro","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/"},"author":{"name":"Julian Toro","@id":"https:\/\/suplos.com\/#\/schema\/person\/548da986b9c5198bba74ab21b97f53b7"},"headline":"Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda","datePublished":"2022-08-11T14:50:56+00:00","dateModified":"2025-07-06T18:07:23+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/"},"wordCount":1397,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/08\/Articulo-portada-unsmushed.png","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/","name":"Nos bastidores do lan\u00e7amento de projetos de tecnologia ao vivo","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/08\/Articulo-portada-unsmushed.png","datePublished":"2022-08-11T14:50:56+00:00","dateModified":"2025-07-06T18:07:23+00:00","description":"Quienes han trabajado en proyectos conocen de primera mano esa sensaci\u00f3n de felicidad indescriptible de sacar un proyecto en vivo.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/08\/Articulo-portada-unsmushed.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/08\/Articulo-portada-unsmushed.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/tras-bambalinas-de-las-salidas-en-vivo-de-los-proyectos-de-tecnologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Tras bambalinas de las salidas en vivo de los proyectos de tecnolog\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/548da986b9c5198bba74ab21b97f53b7","name":"Julian Toro","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/jtoro\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/16034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=16034"}],"version-history":[{"count":1,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/16034\/revisions"}],"predecessor-version":[{"id":16353,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/16034\/revisions\/16353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/16911"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=16034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=16034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=16034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}