{"id":1712,"date":"2021-07-08T16:04:10","date_gmt":"2021-07-08T16:04:10","guid":{"rendered":"https:\/\/suplos.com\/?p=1712"},"modified":"2025-07-09T12:18:11","modified_gmt":"2025-07-09T17:18:11","slug":"transformacion-digital-reactivacion-empresarial","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/","title":{"rendered":"Transforma\u00e7\u00e3o digital: a vacina para a recupera\u00e7\u00e3o dos neg\u00f3cios"},"content":{"rendered":"<p>La situaci\u00f3n actual ha definido muchos retos para todas las empresas que, sin importar su tama\u00f1o, han tenido que buscar soluciones alternativas para dar continuidad a sus negocios. <\/p>\n\n\n\n<p>Es all\u00ed donde se han convertido en lugar com\u00fan expresiones como: \u201ces el momento de reinventarse\u201d, \u201cla resilencia es la clave\u201d o \u201cse requiere de una Transformaci\u00f3n Digital (TD)\u201d. Todas son afirmaciones v\u00e1lidas, pero enfoc\u00e1ndonos en la \u00faltima, <strong>\u00bfcu\u00e1les son los puntos claves para una transformaci\u00f3n digital?<\/strong>, \u00bfes suficiente para lograr una adecuada reactivaci\u00f3n empresarial?<\/p>\n\n\n\n<p>Bastante seguimiento se hace d\u00eda a d\u00eda al proceso de vacunaci\u00f3n del COVID 19 que ejecuta cada pa\u00eds. Algunos m\u00e1s adelantados que otros, al final, independiente del avance, la gran carrera por la inmunidad de reba\u00f1o se ha convertido en la meta m\u00e1xima a lograr en este 2021. <\/p>\n\n\n\n<p>Pero, hay una serie de procesos alternos que deben acompa\u00f1ar el gran esfuerzo cient\u00edfico que se ha logrado: 1) Dar continuidad a los protocolos de auto cuidado, 2) Conservar los h\u00e1bitos de limpieza y 3) Seguir por un tiempo evitando las aglomeraciones. En s\u00edntesis: Potenciar la vacuna con procesos complementarios que lleven al cumplimiento del objetivo m\u00e1ximo enunciado de control masivo del virus.<\/p>\n\n\n\n<p>Haciendo una analog\u00eda al proceso de vacunaci\u00f3n del COVID encontramos la Transformaci\u00f3n Digital: <strong>Es fundamental para todas las empresas<\/strong>, las cuales deben, sin importar su tama\u00f1o, hacer el esfuerzo respectivo para no quedar relegadas al avazallante cambio que enfrenta el ecosistema tecnol\u00f3gico en todos los \u00e1mbitos, pero en especial en el empresarial. <\/p>\n\n\n\n<p>Sin embargo, no es un proceso que funcione bien por s\u00ed solo, <strong>requiere de procesos complementarios para que su ejecuci\u00f3n sea adecuada<\/strong> y finalmente, tenga un impacto positivo en las compa\u00f1\u00edas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo lograr la Transformaci\u00f3n Digital?<\/strong><\/h2>\n\n\n\n<p>Para lograr una adecuada Transformaci\u00f3n Digital es primero importante tener presente:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Transforma\u00e7\u00e3o digital <strong>no implica automatizar por automatizar<\/strong>. Es clave entender el objetivo de la digitalizaci\u00f3n antes de embarcarse en agilizar procesos mal estructurados.<\/li>\n\n\n\n<li>Se puede empezar una TD a todo nivel de empresas y, en la medida en que se vaya creciendo, as\u00ed mismo irse sofisticando.<\/li>\n\n\n\n<li>Se puede acudir <strong>a fuentes \u00e1giles de financiaci\u00f3n digital<\/strong> para lograr el objetivo. Empresas especializadas en soportar a peque\u00f1as, medianas y grandes en lograr la Transformaci\u00f3n Digital aportando los respectivos recursos bajo la figura que m\u00e1s convenga seg\u00fan el tama\u00f1o.<\/li>\n<\/ol>\n\n\n\n<p>Contemplando los puntos anteriores, tambi\u00e9n es clave considerar y reafirmar que la Transformaci\u00f3n Digital debe complementarse con una cultura empresarial que ponga mucho \u00e9nfasis en:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>La TD <strong>la perfeccionan todos y cada uno de los que hacen parte de la empresa<\/strong>, no es responsabilidad &nbsp;solo de equipos 100% t\u00e9cnicos.<\/li>\n\n\n\n<li>Debe ser un <strong>pilar o valor empresarial<\/strong> que cuente con asignaci\u00f3n de recursos, tanto monetarios como de tiempo de cada equipo.<\/li>\n\n\n\n<li>Debe estar en <strong>capacidad de mutar y ser flexible<\/strong> ante los cambios internos y externos.<\/li>\n<\/ol>\n\n\n\n<p>Solo sumando esfuerzos se puede una conseguir una Transformaci\u00f3n Digital robusta y sostenible en el tiempo. No basta solo con la vacuna, <strong>es un compromiso de largo alcance y no de momento<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>La situaci\u00f3n actual ha definido muchos retos para todas las empresas que, sin importar su tama\u00f1o, han tenido que buscar soluciones alternativas para dar continuidad a sus negocios. Es all\u00ed donde se han convertido en lugar com\u00fan expresiones como: \u201ces el momento de reinventarse\u201d, \u201cla resilencia es la clave\u201d o \u201cse requiere de una Transformaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":17397,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-1712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transformacion-digital"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transformaci\u00f3n Digital para la reactivaci\u00f3n comercial<\/title>\n<meta name=\"description\" content=\"\u00bfCu\u00e1les son los puntos claves para una transformaci\u00f3n digital? Con\u00f3celos y analiza c\u00f3mo se podr\u00edan implementar en una compa\u00f1\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/transformacao-digital\/transformacion-digital-reactivacion-empresarial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transformaci\u00f3n Digital para la reactivaci\u00f3n comercial\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1les son los puntos claves para una transformaci\u00f3n digital? Con\u00f3celos y analiza c\u00f3mo se podr\u00edan implementar en una compa\u00f1\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/transformacao-digital\/transformacion-digital-reactivacion-empresarial\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-08T16:04:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T17:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2021\/07\/MicrosoftTeams-image-26-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andres Sarmiento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Sarmiento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/\"},\"author\":{\"name\":\"Andres Sarmiento\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\"},\"headline\":\"Transformaci\u00f3n Digital: la vacuna para la reactivaci\u00f3n empresarial\",\"datePublished\":\"2021-07-08T16:04:10+00:00\",\"dateModified\":\"2025-07-09T17:18:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/\"},\"wordCount\":545,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/MicrosoftTeams-image-26-1.png\",\"articleSection\":[\"Transformaci\u00f3n Digital\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/\",\"name\":\"Transformaci\u00f3n Digital para la reactivaci\u00f3n comercial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/MicrosoftTeams-image-26-1.png\",\"datePublished\":\"2021-07-08T16:04:10+00:00\",\"dateModified\":\"2025-07-09T17:18:11+00:00\",\"description\":\"\u00bfCu\u00e1les son los puntos claves para una transformaci\u00f3n digital? Con\u00f3celos y analiza c\u00f3mo se podr\u00edan implementar en una compa\u00f1\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/MicrosoftTeams-image-26-1.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/MicrosoftTeams-image-26-1.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/transformacion-digital\\\/transformacion-digital-reactivacion-empresarial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transformaci\u00f3n Digital: la vacuna para la reactivaci\u00f3n empresarial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\",\"name\":\"Andres Sarmiento\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/asarmiento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transformaci\u00f3n Digital para la reactivaci\u00f3n comercial","description":"\u00bfCu\u00e1les son los puntos claves para una transformaci\u00f3n digital? Con\u00f3celos y analiza c\u00f3mo se podr\u00edan implementar en una compa\u00f1\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/transformacao-digital\/transformacion-digital-reactivacion-empresarial\/","og_locale":"pt_BR","og_type":"article","og_title":"Transformaci\u00f3n Digital para la reactivaci\u00f3n comercial","og_description":"\u00bfCu\u00e1les son los puntos claves para una transformaci\u00f3n digital? Con\u00f3celos y analiza c\u00f3mo se podr\u00edan implementar en una compa\u00f1\u00eda.","og_url":"https:\/\/suplos.com\/pt\/transformacao-digital\/transformacion-digital-reactivacion-empresarial\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2021-07-08T16:04:10+00:00","article_modified_time":"2025-07-09T17:18:11+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/07\/MicrosoftTeams-image-26-1.png","type":"image\/png"}],"author":"Andres Sarmiento","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Sarmiento","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/"},"author":{"name":"Andres Sarmiento","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897"},"headline":"Transformaci\u00f3n Digital: la vacuna para la reactivaci\u00f3n empresarial","datePublished":"2021-07-08T16:04:10+00:00","dateModified":"2025-07-09T17:18:11+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/"},"wordCount":545,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/07\/MicrosoftTeams-image-26-1.png","articleSection":["Transformaci\u00f3n Digital"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/","url":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/","name":"Transformaci\u00f3n Digital para la reactivaci\u00f3n comercial","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/07\/MicrosoftTeams-image-26-1.png","datePublished":"2021-07-08T16:04:10+00:00","dateModified":"2025-07-09T17:18:11+00:00","description":"\u00bfCu\u00e1les son los puntos claves para una transformaci\u00f3n digital? Con\u00f3celos y analiza c\u00f3mo se podr\u00edan implementar en una compa\u00f1\u00eda.","breadcrumb":{"@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/07\/MicrosoftTeams-image-26-1.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/07\/MicrosoftTeams-image-26-1.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/transformacion-digital\/transformacion-digital-reactivacion-empresarial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Transformaci\u00f3n Digital: la vacuna para la reactivaci\u00f3n empresarial"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897","name":"Andres Sarmiento","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/asarmiento\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/1712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=1712"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/1712\/revisions"}],"predecessor-version":[{"id":17402,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/1712\/revisions\/17402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/17397"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=1712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=1712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=1712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}