{"id":1926,"date":"2021-11-25T19:13:22","date_gmt":"2021-11-25T19:13:22","guid":{"rendered":"https:\/\/suplos.com\/?p=1926"},"modified":"2025-07-06T14:28:26","modified_gmt":"2025-07-06T19:28:26","slug":"desafios-da-cadeia-de-suprimentos-em-2022","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/","title":{"rendered":"Os 6 principais desafios enfrentados pelos executivos da cadeia de suprimentos em 2022"},"content":{"rendered":"<p>Neste artigo, falaremos aos senhores sobre os seis desafios mais importantes que todos os executivos da cadeia de suprimentos enfrentar\u00e3o em 2022. Esses desafios s\u00e3o:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Congestionamento de portos<\/li>\n\n\n\n<li>Aumento dos custos de frete<\/li>\n\n\n\n<li>Reestrutura\u00e7\u00e3o da cadeia de suprimentos<\/li>\n\n\n\n<li>Escassez de materiais e m\u00e3o de obra<\/li>\n\n\n\n<li>Infla\u00e7\u00e3o<\/li>\n\n\n\n<li>Complexidades no planejamento da demanda<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Desafios da cadeia de suprimentos<\/h2>\n\n\n\n<p>A pandemia for\u00e7ou a maneira como as equipes de gerenciamento lidam com as opera\u00e7\u00f5es da cadeia de suprimentos, a <em>aquisi\u00e7\u00e3o<\/em> e as fontes de valor que emanam deles. Embora 2020 e 2021 n\u00e3o tenham sido simples, 2022 n\u00e3o ser\u00e1 a tr\u00e9gua que muitos esperam. Veja a seguir o que os executivos da cadeia de suprimentos devem esperar para o pr\u00f3ximo ano:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Congestionamento de portos<\/strong><\/h3>\n\n\n\n<p>Durante 2020 e 2021, tempos de espera hist\u00f3ricos foram gerados para navios que cruzam portos em todo o mundo. Em outubro de 2021, mais de 50 cont\u00eaineres ficaram retidos em Los Angeles para descarregar cont\u00eaineres da China. Enquanto nos outros portos do mundo h\u00e1 gargalos de navios esperando para serem carregados. Esses gargalos em ambas as extremidades da cadeia de suprimentos levam a atrasos nos tempos de resposta para opera\u00e7\u00f5es de importa\u00e7\u00e3o e exporta\u00e7\u00e3o, o que afeta as cadeias de suprimentos locais.<\/p>\n\n\n\n<p>Por sua <strong>parte, a NCBFAA prop\u00f4s solu\u00e7\u00f5es para rever esse problema, revisando as m\u00e9tricas<\/strong>O fato de que a solu\u00e7\u00e3o para isso ainda est\u00e1 a v\u00e1rios anos de dist\u00e2ncia mostra que a solu\u00e7\u00e3o ainda est\u00e1 a v\u00e1rios anos de dist\u00e2ncia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. <strong>Aumento dos custos de frete<\/strong><\/h3>\n\n\n\n<p>O transporte por tratores e solu\u00e7\u00f5es intermodais atingiu pre\u00e7os recordes em 2020. De 2020 a 2021, os custos tiveram aumentos de dois d\u00edgitos, por exemplo, o custo de camas baixas atingiu uma alta recorde (+27%).<strong>%). O custo do frete mar\u00edtimo e a\u00e9reo ficou pr\u00f3ximo a esses aumentos.<\/strong> Uma combina\u00e7\u00e3o de vari\u00e1veis criou uma tempestade perfeita que dificulta enormemente a movimenta\u00e7\u00e3o de qualquer capacidade de carga.<\/p>\n\n\n\n<p>Para resolver isso, os executivos precisam reestruturar, reavaliar e refor\u00e7ar seus acordos com os <em>transportadoras<\/em>. Enquanto os novos termos que resultar\u00e3o em custos mais altos s\u00e3o o pre\u00e7o a ser pago para ter as mercadorias no prazo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Reestrutura\u00e7\u00e3o da cadeia de suprimentos<\/strong><\/h3>\n\n\n\n<p>O tempo para a reestrutura\u00e7\u00e3o se esgotou e 2022 \u00e9 o ano para fazer isso. <strong>O pr\u00f3ximo ano ser\u00e1 um ano decisivo para as empresas que buscam um fornecimento mais confi\u00e1vel.<\/strong>. Isso pode envolver realoca\u00e7\u00e3o, diversifica\u00e7\u00e3o de fornecedores ou novos acordos com fornecedores. <em>transportadoras<\/em>. Os l\u00edderes devem ser decisivos ao reconhecer que a mudan\u00e7a \u00e9 necess\u00e1ria e estar dispostos a romper e reconstruir acordos que s\u00e3o obsoletos.<\/p>\n\n\n\n<p>Algumas perguntas que devem ser feitas s\u00e3o: O senhor precisa obter fontes mais pr\u00f3ximas do local de opera\u00e7\u00e3o? Aproveitar v\u00e1rios fornecedores para um \u00fanico material? Alinhar-se estrategicamente com parceiros comerciais que tenham mais controle da cadeia de suprimentos?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Falta de materiais e m\u00e3o de obra<\/strong><\/h3>\n\n\n\n<p>A montanha-russa de demiss\u00f5es, trabalho remoto e \u00eaxodo de empregos em 2020 e 2021 ter\u00e1, sem d\u00favida, um impacto em 2022. <strong>A complexidade e a demanda por trabalhos importantes na cadeia de suprimentos tornar\u00e3o a implementa\u00e7\u00e3o da tecnologia e da automa\u00e7\u00e3o ainda mais necess\u00e1ria.<\/strong> para criar coes\u00e3o. Espera-se que as equipes de compras diminuam, e com <em>aprendizado de m\u00e1quina<\/em> A a\u00e7\u00e3o pode ser tomada mais rapidamente.<\/p>\n\n\n\n<p>Isso se soma ao fato de que o ISM (<em>Relat\u00f3rio sobre os neg\u00f3cios<\/em> ) afirma que, para todas as commodities, haver\u00e1 escassez ou aumento de pre\u00e7os. Os executivos podem se adaptar ajustando o <em>prazo de entrega<\/em>A empresa conseguiu repensar seu estoque e diversificar seus fornecedores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Infla\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<p>Os pre\u00e7os cobrados pelos fornecedores est\u00e3o, sem d\u00favida, aumentando e agora \u00e9 uma quest\u00e3o de tempo at\u00e9 que eles sejam repassados aos consumidores. A preocupa\u00e7\u00e3o que surge \u00e9 a seguinte <strong>Como os executivos da cadeia de suprimentos manter\u00e3o os pre\u00e7os baixos sem afetar a cadeia de valor? <\/strong>Aqui, mais uma vez, a resposta est\u00e1 na implementa\u00e7\u00e3o da tecnologia. Os l\u00edderes da cadeia de suprimentos precisar\u00e3o investir em tecnologias melhores, para mobilizar a cadeia de suprimentos para mobilizar <em>informa\u00e7\u00f5es sobre dados<\/em> que geram economia. A <em>aquisi\u00e7\u00e3o<\/em> Torna-se imperativa a necessidade de uma economia mais inteligente, que deve ser capaz de absorver o \u00f4nus da infla\u00e7\u00e3o e dos custos mais altos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6. Complexidades do planejamento da demanda<\/strong><\/h3>\n\n\n\n<p>Nos \u00faltimos 24 meses, os dados gerados para o planejamento da demanda n\u00e3o s\u00e3o confi\u00e1veis. Isso fez com que a proje\u00e7\u00e3o baseada no hist\u00f3rico recente se tornasse incerta. <strong>Os l\u00edderes precisam se concentrar nas tend\u00eancias de curto e longo prazo ao longo do tempo.<\/strong>para formar <em>refer\u00eancias<\/em> que permitem a previs\u00e3o desde os n\u00edveis de estoque at\u00e9 os or\u00e7amentos.<\/p>\n\n\n\n<p>O que est\u00e1 por vir \u00e9, sem d\u00favida, um aumento nos pre\u00e7os, que ter\u00e1 de ser contextualizado, o que foge da an\u00e1lise tradicional dos dados obtidos no \u00faltimo ano.<\/p>\n\n\n\n<p>Em \u00faltima an\u00e1lise, o que est\u00e1 por vir para os l\u00edderes da cadeia de suprimentos \u00e9 a oportunidade de uma avalia\u00e7\u00e3o mais hol\u00edstica e inteligente das opera\u00e7\u00f5es de aquisi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Baseado no artigo em ingl\u00eas: SCM DOJO. Dr. Muddassir Ahmed (Ph.D)<\/p>","protected":false},"excerpt":{"rendered":"<p>En este art\u00edculo te contaremos sobre los 6 retos m\u00e1s importantes que enfrentar\u00e1n todos los ejecutivos en la cadena de suministro en el 2022. Estos retos son: Retos de una cadena de suministro La Pandemia ha forzado la forma en la que los equipos directivos abordan las operaciones de la cadena de suministro, el procurement [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":16953,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-1926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6 retos para las cadenas de suministros en 2022 | Suplos<\/title>\n<meta name=\"description\" content=\"En este art\u00edculo te contaremos sobre los 6 retos m\u00e1s importantes que enfrentar\u00e1n todos los ejecutivos en la cadena de suministro en el 2022.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/desafios-da-cadeia-de-suprimentos-em-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 retos para las cadenas de suministros en 2022 | Suplos\" \/>\n<meta property=\"og:description\" content=\"En este art\u00edculo te contaremos sobre los 6 retos m\u00e1s importantes que enfrentar\u00e1n todos los ejecutivos en la cadena de suministro en el 2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/desafios-da-cadeia-de-suprimentos-em-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-25T19:13:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T19:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniel Obregon Daniel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Obregon Daniel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/\"},\"author\":{\"name\":\"Daniel Obregon Daniel\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/5859c236dc6f1960bec711cb6293e169\"},\"headline\":\"Los 6 retos m\u00e1s importantes que enfrentar\u00e1n los ejecutivos en la Cadena de Suministro en el 2022\",\"datePublished\":\"2021-11-25T19:13:22+00:00\",\"dateModified\":\"2025-07-06T19:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/\"},\"wordCount\":925,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-3.png\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/\",\"name\":\"6 retos para las cadenas de suministros en 2022 | Suplos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-3.png\",\"datePublished\":\"2021-11-25T19:13:22+00:00\",\"dateModified\":\"2025-07-06T19:28:26+00:00\",\"description\":\"En este art\u00edculo te contaremos sobre los 6 retos m\u00e1s importantes que enfrentar\u00e1n todos los ejecutivos en la cadena de suministro en el 2022.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-3.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Articulo-Portada-3.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/retos-cadena-suministro-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los 6 retos m\u00e1s importantes que enfrentar\u00e1n los ejecutivos en la Cadena de Suministro en el 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/5859c236dc6f1960bec711cb6293e169\",\"name\":\"Daniel Obregon Daniel\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/dobregon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 desafios para as cadeias de suprimentos em 2022 | Suplos","description":"Neste artigo, falaremos sobre os seis desafios mais importantes enfrentados por todos os executivos da cadeia de suprimentos em 2022.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/desafios-da-cadeia-de-suprimentos-em-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"6 retos para las cadenas de suministros en 2022 | Suplos","og_description":"En este art\u00edculo te contaremos sobre los 6 retos m\u00e1s importantes que enfrentar\u00e1n todos los ejecutivos en la cadena de suministro en el 2022.","og_url":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/desafios-da-cadeia-de-suprimentos-em-2022\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2021-11-25T19:13:22+00:00","article_modified_time":"2025-07-06T19:28:26+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-3.png","type":"image\/png"}],"author":"Daniel Obregon Daniel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Daniel Obregon Daniel","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/"},"author":{"name":"Daniel Obregon Daniel","@id":"https:\/\/suplos.com\/#\/schema\/person\/5859c236dc6f1960bec711cb6293e169"},"headline":"Los 6 retos m\u00e1s importantes que enfrentar\u00e1n los ejecutivos en la Cadena de Suministro en el 2022","datePublished":"2021-11-25T19:13:22+00:00","dateModified":"2025-07-06T19:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/"},"wordCount":925,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-3.png","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/","name":"6 desafios para as cadeias de suprimentos em 2022 | Suplos","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-3.png","datePublished":"2021-11-25T19:13:22+00:00","dateModified":"2025-07-06T19:28:26+00:00","description":"Neste artigo, falaremos sobre os seis desafios mais importantes enfrentados por todos os executivos da cadeia de suprimentos em 2022.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-3.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2021\/11\/Articulo-Portada-3.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/retos-cadena-suministro-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Los 6 retos m\u00e1s importantes que enfrentar\u00e1n los ejecutivos en la Cadena de Suministro en el 2022"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/5859c236dc6f1960bec711cb6293e169","name":"Daniel Obregon Daniel","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/dobregon\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/1926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=1926"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/1926\/revisions"}],"predecessor-version":[{"id":16954,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/1926\/revisions\/16954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/16953"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=1926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=1926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=1926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}