{"id":2686,"date":"2022-05-05T10:13:53","date_gmt":"2022-05-05T15:13:53","guid":{"rendered":"https:\/\/suplos.com\/?p=2686"},"modified":"2025-07-14T13:06:27","modified_gmt":"2025-07-14T18:06:27","slug":"chegou-a-hora-do-radian","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/soluciones-financieras\/llego-el-momento-de-radian\/","title":{"rendered":"Chegou a hora do RADIAN"},"content":{"rendered":"<p>No contexto das opera\u00e7\u00f5es de pronto pagamento: Factoring ou Confirming, a DIAN entendeu a import\u00e2ncia de ajudar a criar um ambiente adequado para que essas opera\u00e7\u00f5es se desenvolvam da melhor maneira poss\u00edvel e, acima de tudo, sob esquemas de controle claros e transparentes para todos aqueles que interagem, se beneficiam e participam ativamente delas.&nbsp;<\/p>\n\n\n\n<p>O plano da DIAN, desde que iniciou seu piloto no final de 2020, era lan\u00e7ar o live <a href=\"https:\/\/suplos.com\/pt\/solucoes-financeiras\/radiano-novo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema RADIAN at\u00e9 meados de 2021<\/a> e totalmente funcional at\u00e9 o in\u00edcio de 2022. No entanto, depois de disponibilizar projetos de resolu\u00e7\u00e3o para o mercado, a empresa teve que apertar os parafusos, melhorar e fortalecer a proposta de valor final.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que RADIAN?<\/h2>\n\n\n\n<p>H\u00e1 v\u00e1rias raz\u00f5es pelas quais a proposta de criar o sistema RADIAN nasceu, e aqui nos referimos a algumas delas sem definir a totalidade das motiva\u00e7\u00f5es:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Permitir um espa\u00e7o para rastreabilidade e controle das faturas descontadas.&nbsp;<\/li>\n\n\n\n<li>Disponibilizar ao mercado a \"folha de vida\" da fatura e, assim, entre outros motivos, evitar uma cess\u00e3o m\u00faltipla de direitos com poss\u00edvel fraude de diferentes pagamentos no mesmo documento.&nbsp;<\/li>\n\n\n\n<li>Aproveite as ferramentas tecnol\u00f3gicas para tornar as opera\u00e7\u00f5es de desconto de faturas mais \u00e1geis, deixar uma pegada no sistema e dar continuidade aos esfor\u00e7os j\u00e1 avan\u00e7ados associados ao faturamento eletr\u00f4nico.&nbsp;<\/li>\n\n\n\n<li>Estabelecer as bases para abrir as portas, no futuro, para um mercado em que qualquer fornecedor possa encontrar, no mesmo espa\u00e7o, diferentes alternativas ou propostas de financiamento para uma fatura que precise ser adiantada.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Com o mais recente comunicado emitido pela DIAN, no final de abril deste ano, a emiss\u00e3o da Resolu\u00e7\u00e3o 00085 de 2022 especificando (juntamente com o Decreto 1154 de 2020) as diretrizes t\u00e9cnicas e comerciais a serem levadas em conta por todos aqueles que ser\u00e3o participantes do sistema. <br><br>Tamb\u00e9m especifica que, a partir de 13 de julho de 2022, \"os compradores que adquirirem bens e\/ou servi\u00e7os com pagamento em presta\u00e7\u00f5es dever\u00e3o emitir o recibo da fatura de venda e o aviso de recebimento dos bens e\/ou servi\u00e7os eletronicamente, transmitindo-o para valida\u00e7\u00e3o \u00e0 DIAN, usando o servi\u00e7o de faturamento gratuito da DIAN, seu pr\u00f3prio software ou o de um fornecedor de tecnologia\".\u00a0<\/p>\n\n\n\n<p>No final, espera-se que <strong>A partir de julho de 2022, o RADIAN come\u00e7ar\u00e1 a marchar firmemente em dire\u00e7\u00e3o \u00e0 estabiliza\u00e7\u00e3o maci\u00e7a.<\/strong>O objetivo do projeto \u00e9 tornar realidade a m\u00e1xima de ter um pa\u00eds com \"factoring de impacto social\", envolvendo cada vez mais provedores, pagadores, financiadores e parceiros tecnol\u00f3gicos.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Ubicados bajo el contexto de las operaciones de pronto pago: Factoring o Confirming, la DIAN entendi\u00f3 la relevancia que ten\u00eda ayudar a crear un entorno adecuado para que estas se desarrollaran de la mejor forma y, sobre todo, bajo esquemas de control claros y transparentes para todos los que interactuan, se benefician y activamente participan [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":16925,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-2686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soluciones-financieras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lleg\u00f3 el momento de RADIAN<\/title>\n<meta name=\"description\" content=\"Bajo el contexto de Factoring o Confirming, la DIAN entendi\u00f3 la relevancia que ten\u00eda ayudar a crear un entorno adecuado para que estas se desarrollaran de la mejor forma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/solucoes-financeiras\/chegou-a-hora-do-radian\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lleg\u00f3 el momento de RADIAN\" \/>\n<meta property=\"og:description\" content=\"Bajo el contexto de Factoring o Confirming, la DIAN entendi\u00f3 la relevancia que ten\u00eda ayudar a crear un entorno adecuado para que estas se desarrollaran de la mejor forma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/solucoes-financeiras\/chegou-a-hora-do-radian\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T15:13:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T18:06:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/05\/Articulo-portada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andres Sarmiento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Sarmiento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/\"},\"author\":{\"name\":\"Andres Sarmiento\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\"},\"headline\":\"Lleg\u00f3 el momento de RADIAN\",\"datePublished\":\"2022-05-05T15:13:53+00:00\",\"dateModified\":\"2025-07-14T18:06:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/\"},\"wordCount\":477,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Articulo-portada.png\",\"articleSection\":[\"Soluciones financieras\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/\",\"name\":\"Lleg\u00f3 el momento de RADIAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Articulo-portada.png\",\"datePublished\":\"2022-05-05T15:13:53+00:00\",\"dateModified\":\"2025-07-14T18:06:27+00:00\",\"description\":\"Bajo el contexto de Factoring o Confirming, la DIAN entendi\u00f3 la relevancia que ten\u00eda ayudar a crear un entorno adecuado para que estas se desarrollaran de la mejor forma.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Articulo-portada.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Articulo-portada.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/soluciones-financieras\\\/llego-el-momento-de-radian\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lleg\u00f3 el momento de RADIAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\",\"name\":\"Andres Sarmiento\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/asarmiento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chegou a hora do RADIAN","description":"No contexto do Factoring ou Confirming, a DIAN entendeu a import\u00e2ncia de ajudar a criar um ambiente adequado para que eles se desenvolvam da melhor maneira poss\u00edvel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/solucoes-financeiras\/chegou-a-hora-do-radian\/","og_locale":"pt_BR","og_type":"article","og_title":"Lleg\u00f3 el momento de RADIAN","og_description":"Bajo el contexto de Factoring o Confirming, la DIAN entendi\u00f3 la relevancia que ten\u00eda ayudar a crear un entorno adecuado para que estas se desarrollaran de la mejor forma.","og_url":"https:\/\/suplos.com\/pt\/solucoes-financeiras\/chegou-a-hora-do-radian\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2022-05-05T15:13:53+00:00","article_modified_time":"2025-07-14T18:06:27+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/05\/Articulo-portada.png","type":"image\/png"}],"author":"Andres Sarmiento","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Sarmiento","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/"},"author":{"name":"Andres Sarmiento","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897"},"headline":"Lleg\u00f3 el momento de RADIAN","datePublished":"2022-05-05T15:13:53+00:00","dateModified":"2025-07-14T18:06:27+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/"},"wordCount":477,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/05\/Articulo-portada.png","articleSection":["Soluciones financieras"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/","url":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/","name":"Chegou a hora do RADIAN","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/05\/Articulo-portada.png","datePublished":"2022-05-05T15:13:53+00:00","dateModified":"2025-07-14T18:06:27+00:00","description":"No contexto do Factoring ou Confirming, a DIAN entendeu a import\u00e2ncia de ajudar a criar um ambiente adequado para que eles se desenvolvam da melhor maneira poss\u00edvel.","breadcrumb":{"@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/05\/Articulo-portada.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/05\/Articulo-portada.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/soluciones-financieras\/llego-el-momento-de-radian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"Lleg\u00f3 el momento de RADIAN"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897","name":"Andres Sarmiento","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/asarmiento\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/2686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=2686"}],"version-history":[{"count":3,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/2686\/revisions"}],"predecessor-version":[{"id":17735,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/2686\/revisions\/17735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/16925"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=2686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=2686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=2686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}