{"id":2892,"date":"2022-11-03T11:06:53","date_gmt":"2022-11-03T16:06:53","guid":{"rendered":"https:\/\/suplos.com\/?p=2892"},"modified":"2025-07-06T12:56:35","modified_gmt":"2025-07-06T17:56:35","slug":"quanto-custa-a-implementacao-do-software-scm","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/","title":{"rendered":"Quanto custa a implementa\u00e7\u00e3o do software SCM?"},"content":{"rendered":"<p>Muitas organiza\u00e7\u00f5es est\u00e3o finalizando seu or\u00e7amento para 2023 e querem saber quanto pode custar um projeto de implementa\u00e7\u00e3o de sourcing. Neste blog, apresentamos ao senhor alguns n\u00fameros do mercado e os benef\u00edcios.&nbsp;&nbsp;<\/p>\n\n\n<p>De acordo com um estudo realizado pela Capterra, o custo m\u00e9dio \u00e9 de US$200.000 a US$450.000, dependendo da complexidade da solu\u00e7\u00e3o. No entanto, \u00e9 importante observar que esse estudo foi realizado em pa\u00edses da Europa e nos EUA.\u00a0\u00a0<\/p>\n<h2>Avalia\u00e7\u00e3o de custos na implementa\u00e7\u00e3o do SCM<\/h2>\n\n\n<p>Esses custos, sem d\u00favida, n\u00e3o correspondem \u00e0 realidade latino-americana de enfrentar moedas desvalorizadas e muitas complexidades na cadeia de suprimentos. Um investimento em tecnologia apenas para a implementa\u00e7\u00e3o de uma solu\u00e7\u00e3o desse tipo, do nosso ponto de vista, \u00e9 desproporcional.&nbsp;&nbsp;<\/p>\n\n\n\n<p>De acordo com o estudo, apesar do custo, \u00e9 poss\u00edvel obter at\u00e9 <strong>900% ROI em 3 anos<\/strong> desde que a solu\u00e7\u00e3o foi implementada. Os benef\u00edcios esperados s\u00e3o:&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/image.png\" alt=\"\" class=\"wp-image-2893\"\/><\/figure>\n\n\n\n<p>Aumento da produtividade da equipe de compras, devido \u00e0 redu\u00e7\u00e3o de tarefas manuais.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/image-1.png\" alt=\"\" class=\"wp-image-2895\"\/><\/figure>\n\n\n\n<p>Economia m\u00e9dia em aquisi\u00e7\u00f5es para v\u00e1rias categorias, devido \u00e0 contrata\u00e7\u00e3o de mais e melhores fornecedores.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/image-2.png\" alt=\"\" class=\"wp-image-2897\"\/><\/figure>\n\n\n\n<p>Maior velocidade no ciclo da pesquisa ao contrato, devido \u00e0s automa\u00e7\u00f5es da solu\u00e7\u00e3o de e-sourcing e leil\u00e3o que agiliza a intera\u00e7\u00e3o com o fornecedor.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/image-3.png\" alt=\"\" class=\"wp-image-2898\"\/><\/figure>\n\n\n\n<p>Aumento da velocidade de contrata\u00e7\u00e3o por meio de fluxos de aprova\u00e7\u00e3o autom\u00e1ticos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/image-4.png\" alt=\"\" class=\"wp-image-2899\"\/><\/figure>\n\n\n\n<p>Gerenciamento do banco de dados de fornecedores devido \u00e0 sua centraliza\u00e7\u00e3o e alta confiabilidade, pois s\u00e3o validados do ponto de vista t\u00e9cnico e financeiro.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/image-5.png\" alt=\"\" class=\"wp-image-2900\"\/><\/figure>\n\n\n\n<p>Riscos da cadeia de suprimentos, devido \u00e0 sele\u00e7\u00e3o mais rigorosa e precisa de fornecedores com an\u00e1lise de risco em tempo real.&nbsp;<\/p>\n\n\n\n<p>P.S. Na Suplos, temos orgulho de mostrar que, com a tecnologia e a efici\u00eancia que geramos nos \u00faltimos 8 anos, temos taxas que s\u00e3o apenas uma fra\u00e7\u00e3o dos custos descritos. Portanto, podemos oferecer um ROI muito maior a todas as organiza\u00e7\u00f5es latino-americanas em menos tempo. Entre em contato conosco.&nbsp;<\/p>\n\n\n\n<p>Dados extra\u00eddos de: Capterra\/Science Soft.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Muchas organizaciones est\u00e1n terminando su presupuesto para el 2023 y quieren establecer cu\u00e1nto les podr\u00eda costar un proyecto de implementaci\u00f3n de Sourcing. En este blog te contamos algunos n\u00fameros de mercado y los beneficios.&nbsp;&nbsp; De acuerdo con un estudio realizado por Capterra el costo promedio que le arroja es de US$200.000 a US$450.000 dependiendo de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":16899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-2892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?<\/title>\n<meta name=\"description\" content=\"Muchas organizaciones est\u00e1n terminando su presupuesto para el 2023 y quieren establecer cu\u00e1nto les podr\u00eda costar un proyecto de implementaci\u00f3n de Sourcing.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/quanto-custa-a-implementacao-do-software-scm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?\" \/>\n<meta property=\"og:description\" content=\"Muchas organizaciones est\u00e1n terminando su presupuesto para el 2023 y quieren establecer cu\u00e1nto les podr\u00eda costar un proyecto de implementaci\u00f3n de Sourcing.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/quanto-custa-a-implementacao-do-software-scm\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-03T16:06:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T17:56:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/Articulo-portada-2-unsmushed.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniel Obregon Daniel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Obregon Daniel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/\"},\"author\":{\"name\":\"Daniel Obregon Daniel\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/5859c236dc6f1960bec711cb6293e169\"},\"headline\":\"\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?\",\"datePublished\":\"2022-11-03T16:06:53+00:00\",\"dateModified\":\"2025-07-06T17:56:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/\"},\"wordCount\":401,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Articulo-portada-2-unsmushed.png\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/\",\"name\":\"\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Articulo-portada-2-unsmushed.png\",\"datePublished\":\"2022-11-03T16:06:53+00:00\",\"dateModified\":\"2025-07-06T17:56:35+00:00\",\"description\":\"Muchas organizaciones est\u00e1n terminando su presupuesto para el 2023 y quieren establecer cu\u00e1nto les podr\u00eda costar un proyecto de implementaci\u00f3n de Sourcing.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Articulo-portada-2-unsmushed.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Articulo-portada-2-unsmushed.png\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/5859c236dc6f1960bec711cb6293e169\",\"name\":\"Daniel Obregon Daniel\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/dobregon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quanto custa a implementa\u00e7\u00e3o do software SCM?","description":"Muitas organiza\u00e7\u00f5es est\u00e3o finalizando seu or\u00e7amento para 2023 e querem saber quanto poder\u00e1 custar um projeto de implementa\u00e7\u00e3o de sourcing.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/quanto-custa-a-implementacao-do-software-scm\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?","og_description":"Muchas organizaciones est\u00e1n terminando su presupuesto para el 2023 y quieren establecer cu\u00e1nto les podr\u00eda costar un proyecto de implementaci\u00f3n de Sourcing.","og_url":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/quanto-custa-a-implementacao-do-software-scm\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2022-11-03T16:06:53+00:00","article_modified_time":"2025-07-06T17:56:35+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/Articulo-portada-2-unsmushed.png","type":"image\/png"}],"author":"Daniel Obregon Daniel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Daniel Obregon Daniel","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/"},"author":{"name":"Daniel Obregon Daniel","@id":"https:\/\/suplos.com\/#\/schema\/person\/5859c236dc6f1960bec711cb6293e169"},"headline":"\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?","datePublished":"2022-11-03T16:06:53+00:00","dateModified":"2025-07-06T17:56:35+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/"},"wordCount":401,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/Articulo-portada-2-unsmushed.png","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/","name":"Quanto custa a implementa\u00e7\u00e3o do software SCM?","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/Articulo-portada-2-unsmushed.png","datePublished":"2022-11-03T16:06:53+00:00","dateModified":"2025-07-06T17:56:35+00:00","description":"Muitas organiza\u00e7\u00f5es est\u00e3o finalizando seu or\u00e7amento para 2023 e querem saber quanto poder\u00e1 custar um projeto de implementa\u00e7\u00e3o de sourcing.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/Articulo-portada-2-unsmushed.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2022\/11\/Articulo-portada-2-unsmushed.png","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/cuanto-cuesta-la-implementacion-de-un-software-de-scm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1nto cuesta la implementaci\u00f3n de un software de SCM?"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/5859c236dc6f1960bec711cb6293e169","name":"Daniel Obregon Daniel","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/dobregon\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/2892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=2892"}],"version-history":[{"count":1,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/2892\/revisions"}],"predecessor-version":[{"id":16161,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/2892\/revisions\/16161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/16899"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=2892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=2892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=2892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}