{"id":3100,"date":"2023-03-10T09:06:36","date_gmt":"2023-03-10T14:06:36","guid":{"rendered":"https:\/\/suplos.com\/?p=3100"},"modified":"2025-07-06T11:28:02","modified_gmt":"2025-07-06T16:28:02","slug":"como-dar-lances-e-nao-falhar-na-tentativa","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/","title":{"rendered":"<strong>Como dar lances e n\u00e3o falhar na tentativa<\/strong>\u00a0"},"content":{"rendered":"<p>O cotidiano de muitas empresas \u00e9 marcado pela necessidade de encontrar solu\u00e7\u00f5es, seja para a aquisi\u00e7\u00e3o de bens ou servi\u00e7os que ajudem a dar continuidade \u00e0s suas opera\u00e7\u00f5es. <strong>Nesse contexto, eles devem recorrer a terceiros adequados para contribuir com o cumprimento dos objetivos estrat\u00e9gicos de curto, m\u00e9dio e longo prazo.<\/strong> \u00c9 nesse ponto que a execu\u00e7\u00e3o de processos de licita\u00e7\u00e3o se torna uma pr\u00e1tica comum. Infelizmente, para alguns, ela se torna o in\u00edcio e o fim imediatos do processo devido \u00e0 falta de orienta\u00e7\u00e3o adequada para sua conclus\u00e3o.&nbsp;<\/p>\n\n\n\n<p>A estrutura\u00e7\u00e3o de uma licita\u00e7\u00e3o busca abranger todas as perspectivas: jur\u00eddica, financeira, funcional, t\u00e9cnica, operacional, entre outras, a fim de encontrar o candidato ideal que possa suportar a necessidade estrat\u00e9gica. Entretanto, em muitos casos, a sobrecarga na demanda por especifica\u00e7\u00f5es, a alta carga documental e, principalmente, a falta de uma ferramenta adequada de rastreabilidade e controle tornam o processo incontrol\u00e1vel, levando, em alguns casos, ao seu cancelamento precoce.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que deve ser levado em conta na licita\u00e7\u00e3o?\u00a0<\/h2>\n\n\n\n<p>\u00c9 importante ter alguns fatores-chave em vigor antes de iniciar um processo de licita\u00e7\u00e3o que garantir\u00e1 que o senhor n\u00e3o desista no meio do caminho nem cometa erros:&nbsp;<\/p>\n\n\n<h3 class=\"wp-block-heading\">Seja muito claro sobre o objetivo do processo que o senhor deseja iniciar.<\/h3>\n<p><br \/>Pode parecer b\u00e1sico, mas, em alguns casos, a falta de precis\u00e3o pode levar os proponentes errados \u00e0 mesa de negocia\u00e7\u00f5es ou atrasar o processo por n\u00e3o encontrar partes interessadas.\u00a0<\/p>\n\n<h3>Ter ferramentas de suporte digital<\/h3>\n<p><br \/><br \/>O desenvolvimento de uma licita\u00e7\u00e3o baseada em processos manuais e f\u00edsicos pode se tornar um verdadeiro pesadelo, pois n\u00e3o h\u00e1 controle sobre quais informa\u00e7\u00f5es est\u00e3o atualizadas, onde s\u00e3o mantidos os documentos de cada licitante, quem est\u00e1 interessado em participar, como organizar as informa\u00e7\u00f5es sem misturar os aspectos jur\u00eddicos, financeiros ou funcionais.\u00a0<\/p>\n\n<h3>Definir claramente os recursos a serem alocados<\/h3>\n<p><br \/><br \/>Pode acontecer que o or\u00e7amento a ser alocado como limite ou fronteira n\u00e3o seja especificado no momento certo e, ent\u00e3o, na metade do processo, fica claro que n\u00e3o h\u00e1 como avan\u00e7ar com o projeto.\u00a0<\/p>\n\n\n<p>A melhor alternativa \u00e9 realizar um processo digital e rastre\u00e1vel que permita a defini\u00e7\u00e3o de candidatos adequados, que divida claramente cada cap\u00edtulo a ser gerenciado pelos licitantes e onde cada um possa ser controlado (desde a entrega de documentos at\u00e9 a evolu\u00e7\u00e3o do processo). Da mesma forma, o sistema deve permitir o esclarecimento on-line de d\u00favidas e dar a cada licitante uma vis\u00e3o clara de como o processo est\u00e1 progredindo. Por fim, e esse n\u00e3o \u00e9 um ponto de menor import\u00e2ncia, ele deve oferecer transpar\u00eancia do processo passo a passo, em que uma fun\u00e7\u00e3o de auditoria possa corroborar a execu\u00e7\u00e3o adequada da licita\u00e7\u00e3o.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>El d\u00eda a d\u00eda de muchas empresas est\u00e1 marcado por la necesidad de encontrar soluciones, ya sea para la adquisici\u00f3n de bienes o servicios que ayuden a dar continuidad a su operaci\u00f3n. En este contexto, deben acudir a terceros id\u00f3neos que contribuyan al cumplimiento de los objetivos estrat\u00e9gicos a corto, mediano y largo plazo. Es [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":16888,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-3100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo licitar y no fallar en el intento\u00a0<\/title>\n<meta name=\"description\" content=\"La cotidianidad de las empresas est\u00e1 marcada por la necesidad de encontrar soluciones, ya sea en bienes o servicios que ayuden en la operaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/como-dar-lances-e-nao-falhar-na-tentativa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo licitar y no fallar en el intento\u00a0\" \/>\n<meta property=\"og:description\" content=\"La cotidianidad de las empresas est\u00e1 marcada por la necesidad de encontrar soluciones, ya sea en bienes o servicios que ayuden en la operaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/como-dar-lances-e-nao-falhar-na-tentativa\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-10T14:06:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T16:28:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2023\/03\/Articulo-portada-unsmushed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Sarmiento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Sarmiento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/\"},\"author\":{\"name\":\"Andres Sarmiento\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\"},\"headline\":\"C\u00f3mo licitar y no fallar en el intento\u00a0\",\"datePublished\":\"2023-03-10T14:06:36+00:00\",\"dateModified\":\"2025-07-06T16:28:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/\"},\"wordCount\":494,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Articulo-portada-unsmushed.jpg\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/\",\"name\":\"C\u00f3mo licitar y no fallar en el intento\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Articulo-portada-unsmushed.jpg\",\"datePublished\":\"2023-03-10T14:06:36+00:00\",\"dateModified\":\"2025-07-06T16:28:02+00:00\",\"description\":\"La cotidianidad de las empresas est\u00e1 marcada por la necesidad de encontrar soluciones, ya sea en bienes o servicios que ayuden en la operaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Articulo-portada-unsmushed.jpg\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Articulo-portada-unsmushed.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/como-licitar-y-no-fallar-en-el-intento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo licitar y no fallar en el intento\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/adc5555f4698ef7d67726eeeeebfc897\",\"name\":\"Andres Sarmiento\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/asarmiento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como dar lances e n\u00e3o falhar na tentativa\u00a0","description":"O cotidiano das empresas \u00e9 marcado pela necessidade de encontrar solu\u00e7\u00f5es, seja em bens ou servi\u00e7os que auxiliem na opera\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/como-dar-lances-e-nao-falhar-na-tentativa\/","og_locale":"pt_BR","og_type":"article","og_title":"C\u00f3mo licitar y no fallar en el intento\u00a0","og_description":"La cotidianidad de las empresas est\u00e1 marcada por la necesidad de encontrar soluciones, ya sea en bienes o servicios que ayuden en la operaci\u00f3n.","og_url":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/como-dar-lances-e-nao-falhar-na-tentativa\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2023-03-10T14:06:36+00:00","article_modified_time":"2025-07-06T16:28:02+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/03\/Articulo-portada-unsmushed.jpg","type":"image\/jpeg"}],"author":"Andres Sarmiento","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Sarmiento","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/"},"author":{"name":"Andres Sarmiento","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897"},"headline":"C\u00f3mo licitar y no fallar en el intento\u00a0","datePublished":"2023-03-10T14:06:36+00:00","dateModified":"2025-07-06T16:28:02+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/"},"wordCount":494,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/03\/Articulo-portada-unsmushed.jpg","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/","name":"Como dar lances e n\u00e3o falhar na tentativa\u00a0","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/03\/Articulo-portada-unsmushed.jpg","datePublished":"2023-03-10T14:06:36+00:00","dateModified":"2025-07-06T16:28:02+00:00","description":"O cotidiano das empresas \u00e9 marcado pela necessidade de encontrar solu\u00e7\u00f5es, seja em bens ou servi\u00e7os que auxiliem na opera\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/03\/Articulo-portada-unsmushed.jpg","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2023\/03\/Articulo-portada-unsmushed.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/como-licitar-y-no-fallar-en-el-intento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo licitar y no fallar en el intento\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/adc5555f4698ef7d67726eeeeebfc897","name":"Andres Sarmiento","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/asarmiento\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/3100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=3100"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/3100\/revisions"}],"predecessor-version":[{"id":16889,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/3100\/revisions\/16889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/16888"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=3100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=3100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=3100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}