{"id":882,"date":"2020-05-05T23:45:00","date_gmt":"2020-05-05T23:45:00","guid":{"rendered":"https:\/\/suplos.com\/?p=882"},"modified":"2025-07-09T22:07:01","modified_gmt":"2025-07-10T03:07:01","slug":"transformar-a-gestao-de-suprimentos","status":"publish","type":"post","link":"https:\/\/suplos.com\/pt\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/","title":{"rendered":"3 tend\u00eancias que est\u00e3o transformando a gest\u00e3o de suprimentos em tempos de COVID-19"},"content":{"rendered":"<p>Sem d\u00favida, o uso de diferentes tecnologias est\u00e1 mudando os processos e as intera\u00e7\u00f5es comerciais. \u00c9 por isso que,&nbsp;<strong>o grande desafio \u00e9 transformar o gerenciamento de suprimentos em um processo mais conectado, inteligente e transparente.<\/strong>&nbsp;Aproveitar o uso da tecnologia.<\/p>\n\n\n\n<p>O papel das \u00e1reas de compras e suprimentos est\u00e1 mudando, por isso \u00e9 fundamental adaptar-se a novos contextos e incorporar tend\u00eancias em seus processos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ferramentas de nuvem e software como servi\u00e7o<\/h2>\n\n\n\n<p>A constante evolu\u00e7\u00e3o da tecnologia tamb\u00e9m afeta a cadeia de suprimentos. \u00c9 por isso que,&nbsp;<strong>As plataformas para seu gerenciamento foram reinventadas para oferecer inova\u00e7\u00e3o, emoldurada pela facilidade de uso e por uma melhor experi\u00eancia no gerenciamento de processos.<\/strong><\/p>\n\n\n\n<p>Dessa forma, as plataformas de nuvem permitem que os processos de neg\u00f3cios sejam executados de forma mais eficiente, flex\u00edvel e escalon\u00e1vel, pois, com uma \u00fanica conex\u00e3o com a rede de suprimentos, elas podem&nbsp;<strong>interagindo os diferentes&nbsp;<em>partes interessadas&nbsp;<\/em>e trabalhar juntos.<\/strong>&nbsp;Por outro lado, a tecnologia de nuvem permite integra\u00e7\u00f5es mais perfeitas com outros sistemas, como ERP ou software de contabilidade, possibilitando um melhor desempenho da equipe e uma melhoria substancial na efici\u00eancia dos neg\u00f3cios.<\/p>\n\n\n\n<p>Al\u00e9m disso, o&nbsp;<em>Software como servi\u00e7o<\/em>&nbsp;A gest\u00e3o de sourcing foi implementada, permitindo que as \u00e1reas de compras se concentrem na&nbsp;<em>n\u00facleo<\/em>&nbsp;e economizar recursos, transferindo a responsabilidade pelos neg\u00f3cios e pela&nbsp;<strong>mais espec\u00edficos, como infraestrutura, implementa\u00e7\u00f5es e manuten\u00e7\u00e3o tecnol\u00f3gica para especialistas.<\/strong><\/p>\n\n\n\n<p>Assim, essas duas tend\u00eancias se tornaram grandes aliadas do sourcing, porque&nbsp;<strong>Eles conseguem remover as barreiras entre os processos, transformando a cadeia de suprimentos em um ecossistema integrado.<\/strong>&nbsp;e acess\u00edvel aos seus acionistas, desde os tomadores de decis\u00e3o at\u00e9 os fornecedores de bens e servi\u00e7os. Portanto, \u00e9 essencial tirar proveito das inova\u00e7\u00f5es no campo tecnol\u00f3gico para gerar competitividade nas empresas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise de dados na cadeia de suprimentos<\/h2>\n\n\n\n<p>Sem d\u00favida, os processos de sourcing geram uma grande quantidade de dados que aumentam a capacidade de tornar vis\u00edvel o gerenciamento dos neg\u00f3cios.&nbsp;<strong>Desde o planejamento, a produ\u00e7\u00e3o, a busca de fornecedores at\u00e9 o pagamento de faturas s\u00e3o fontes de dados.&nbsp;<\/strong>que, quando processadas, tornam-se informa\u00e7\u00f5es relevantes. Essas informa\u00e7\u00f5es tornam-se relevantes para a tomada de decis\u00f5es que podem impulsionar estrat\u00e9gias de redu\u00e7\u00e3o de custos e gerar valor a partir das \u00e1reas de compras.<\/p>\n\n\n\n<p>A an\u00e1lise avan\u00e7ada usa v\u00e1rios algoritmos para reconhecer padr\u00f5es em conjuntos de dados, encontrando assim tend\u00eancias que podem afetar o gerenciamento de suprimentos. A an\u00e1lise desses dados e sua coleta precisa melhoram a tomada de decis\u00f5es, o gerenciamento de riscos e o desenvolvimento de processos. Alguns usos da an\u00e1lise de dados&nbsp;<strong>pode ocorrer no planejamento das despesas anuais, nas negocia\u00e7\u00f5es com fornecedores ou na otimiza\u00e7\u00e3o das equipes de compras.<\/strong><\/p>\n\n\n\n<p>Ao aproveitar essas informa\u00e7\u00f5es, as organiza\u00e7\u00f5es podem n\u00e3o apenas responder rapidamente aos incidentes, mas tamb\u00e9m antecip\u00e1-los e preveni-los de forma eficaz. Dessa forma, o gerenciamento de suprimentos assume um papel mais estrat\u00e9gico dentro das organiza\u00e7\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conex\u00e3o e escalabilidade na cadeia de suprimentos<\/h2>\n\n\n\n<p>A nova maneira de abordar a gest\u00e3o de suprimentos levou ao aprimoramento de certas caracter\u00edsticas que a diferenciam radicalmente das formas tradicionais. As novas necessidades dos neg\u00f3cios trazem consigo uma nova&nbsp;<strong>cadeia de suprimentos mais conectada e escal\u00e1vel.<\/strong><\/p>\n\n\n\n<p>Conectar fornecedores, distribuidores, compradores, \u00e1reas de usu\u00e1rios e tomadores de decis\u00e3o \u00e9 essencial para passar do trabalho individual para o trabalho colaborativo, inovador e mais transparente. Um dos mais importantes<strong>s benef\u00edcios de ter uma rede conectada s\u00e3o a visibilidade em tempo real dos processos,<\/strong>&nbsp;que promove o dinamismo e apoia as decis\u00f5es que afetam os neg\u00f3cios.<\/p>\n\n\n\n<p>Esse ecossistema tamb\u00e9m permite a colabora\u00e7\u00e3o entre os membros da \u00e1rea, o r\u00e1pido ajuste \u00e0s mudan\u00e7as e o acesso a informa\u00e7\u00f5es corretas e oportunas em todas as etapas do processo.<\/p>\n\n\n\n<p>Essas s\u00e3o apenas algumas das tend\u00eancias que est\u00e3o transformando o gerenciamento de suprimentos, levando-o a um contexto mais integrado e estrat\u00e9gico.&nbsp;<strong>\u00c9 hora de colocar a ado\u00e7\u00e3o de novas tecnologias no roteiro<\/strong>&nbsp;que aprimoram os recursos das \u00e1reas de compras das empresas. &nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Sin duda, el uso de distintas tecnolog\u00edas est\u00e1 cambiando los procesos e interacciones de los negocios. Por eso,&nbsp;el gran reto es transformar la gesti\u00f3n de abastecimiento en un proceso m\u00e1s conectado, inteligente y transparente&nbsp;apalac\u00e1ndose en el uso de tecnolog\u00eda. El rol de las \u00e1reas de compras y abastecimiento est\u00e1 cambiando, por eso es clave adaptarse [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17529,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-abastecimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 tendencias que transforman la gesti\u00f3n de abastecimiento<\/title>\n<meta name=\"description\" content=\"el gran reto es transformar la gesti\u00f3n de abastecimiento en un proceso m\u00e1s conectado en tiempos de Covid-19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/transformar-a-gestao-de-suprimentos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 tendencias que transforman la gesti\u00f3n de abastecimiento\" \/>\n<meta property=\"og:description\" content=\"el gran reto es transformar la gesti\u00f3n de abastecimiento en un proceso m\u00e1s conectado en tiempos de Covid-19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/transformar-a-gestao-de-suprimentos\/\" \/>\n<meta property=\"og:site_name\" content=\"suplos.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SuplosLatam\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T23:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-10T03:07:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suplos.com\/wp-content\/uploads\/2020\/05\/transforma-abastecimiento.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tatiana Calero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tatiana Calero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/\"},\"author\":{\"name\":\"Tatiana Calero\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/94dedd93b3d634d7b59f4e5299e6bb26\"},\"headline\":\"3 tendencias que transforman la gesti\u00f3n de abastecimiento en tiempos de COVID19\",\"datePublished\":\"2020-05-05T23:45:00+00:00\",\"dateModified\":\"2025-07-10T03:07:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/\"},\"wordCount\":776,\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/transforma-abastecimiento.png\",\"articleSection\":[\"Gesti\u00f3n de Abastecimiento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/\",\"name\":\"3 tendencias que transforman la gesti\u00f3n de abastecimiento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/transforma-abastecimiento.png\",\"datePublished\":\"2020-05-05T23:45:00+00:00\",\"dateModified\":\"2025-07-10T03:07:01+00:00\",\"description\":\"el gran reto es transformar la gesti\u00f3n de abastecimiento en un proceso m\u00e1s conectado en tiempos de Covid-19.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/transforma-abastecimiento.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/transforma-abastecimiento.png\",\"width\":1920,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suplos.com\\\/gestion-de-abastecimiento\\\/transforman-gestion-abastecimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/suplos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 tendencias que transforman la gesti\u00f3n de abastecimiento en tiempos de COVID19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#website\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"name\":\"Suplos\",\"description\":\"Software para la gesti\u00f3n de Abastecimiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suplos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#organization\",\"name\":\"Suplos\",\"url\":\"https:\\\/\\\/suplos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"contentUrl\":\"https:\\\/\\\/suplos.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-completo-250x250px.png\",\"width\":250,\"height\":250,\"caption\":\"Suplos\"},\"image\":{\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SuplosLatam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/suplos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suplos.com\\\/#\\\/schema\\\/person\\\/94dedd93b3d634d7b59f4e5299e6bb26\",\"name\":\"Tatiana Calero\",\"sameAs\":[\"http:\\\/\\\/suplos.com\"],\"url\":\"https:\\\/\\\/suplos.com\\\/pt\\\/author\\\/tatiana-calero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 tend\u00eancias que est\u00e3o transformando a gest\u00e3o de suprimentos","description":"o grande desafio \u00e9 transformar a gest\u00e3o de suprimentos em um processo mais conectado em tempos de Covid-19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/transformar-a-gestao-de-suprimentos\/","og_locale":"pt_BR","og_type":"article","og_title":"3 tendencias que transforman la gesti\u00f3n de abastecimiento","og_description":"el gran reto es transformar la gesti\u00f3n de abastecimiento en un proceso m\u00e1s conectado en tiempos de Covid-19.","og_url":"https:\/\/suplos.com\/pt\/gerenciamento-de-suprimentos\/transformar-a-gestao-de-suprimentos\/","og_site_name":"suplos.com","article_publisher":"https:\/\/www.facebook.com\/SuplosLatam","article_published_time":"2020-05-05T23:45:00+00:00","article_modified_time":"2025-07-10T03:07:01+00:00","og_image":[{"width":1920,"height":650,"url":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/05\/transforma-abastecimiento.png","type":"image\/png"}],"author":"Tatiana Calero","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Tatiana Calero","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/#article","isPartOf":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/"},"author":{"name":"Tatiana Calero","@id":"https:\/\/suplos.com\/#\/schema\/person\/94dedd93b3d634d7b59f4e5299e6bb26"},"headline":"3 tendencias que transforman la gesti\u00f3n de abastecimiento en tiempos de COVID19","datePublished":"2020-05-05T23:45:00+00:00","dateModified":"2025-07-10T03:07:01+00:00","mainEntityOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/"},"wordCount":776,"publisher":{"@id":"https:\/\/suplos.com\/#organization"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/05\/transforma-abastecimiento.png","articleSection":["Gesti\u00f3n de Abastecimiento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/","url":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/","name":"3 tend\u00eancias que est\u00e3o transformando a gest\u00e3o de suprimentos","isPartOf":{"@id":"https:\/\/suplos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/#primaryimage"},"image":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/05\/transforma-abastecimiento.png","datePublished":"2020-05-05T23:45:00+00:00","dateModified":"2025-07-10T03:07:01+00:00","description":"o grande desafio \u00e9 transformar a gest\u00e3o de suprimentos em um processo mais conectado em tempos de Covid-19.","breadcrumb":{"@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/#primaryimage","url":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/05\/transforma-abastecimiento.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2020\/05\/transforma-abastecimiento.png","width":1920,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/suplos.com\/gestion-de-abastecimiento\/transforman-gestion-abastecimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/suplos.com\/"},{"@type":"ListItem","position":2,"name":"3 tendencias que transforman la gesti\u00f3n de abastecimiento en tiempos de COVID19"}]},{"@type":"WebSite","@id":"https:\/\/suplos.com\/#website","url":"https:\/\/suplos.com\/","name":"Suplos","description":"Software de gerenciamento de suprimentos","publisher":{"@id":"https:\/\/suplos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suplos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/suplos.com\/#organization","name":"Suplos","url":"https:\/\/suplos.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/","url":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","contentUrl":"https:\/\/suplos.com\/wp-content\/uploads\/2025\/05\/cropped-Logo-completo-250x250px.png","width":250,"height":250,"caption":"Suplos"},"image":{"@id":"https:\/\/suplos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SuplosLatam","https:\/\/www.linkedin.com\/company\/suplos"]},{"@type":"Person","@id":"https:\/\/suplos.com\/#\/schema\/person\/94dedd93b3d634d7b59f4e5299e6bb26","name":"Tatiana Calero","sameAs":["http:\/\/suplos.com"],"url":"https:\/\/suplos.com\/pt\/author\/tatiana-calero\/"}]}},"_links":{"self":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/comments?post=882"}],"version-history":[{"count":2,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/882\/revisions"}],"predecessor-version":[{"id":17530,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/posts\/882\/revisions\/17530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media\/17529"}],"wp:attachment":[{"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/media?parent=882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/categories?post=882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suplos.com\/pt\/wp-json\/wp\/v2\/tags?post=882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}